{"id":19296,"date":"2024-02-17T02:29:14","date_gmt":"2024-02-17T01:29:14","guid":{"rendered":"https:\/\/canoes-loisirs.com\/curso-de-piraguismo-en-dordona\/vitrac-castelnaud\/"},"modified":"2026-02-03T22:35:44","modified_gmt":"2026-02-03T21:35:44","slug":"vitrac-castelnaud","status":"publish","type":"page","link":"https:\/\/canoes-loisirs.com\/es\/curso-de-piraguismo-en-dordona\/vitrac-castelnaud\/","title":{"rendered":"Vitrac &gt; Castelnaud &#8211; Valle de los 2 Castillos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"19296\" class=\"elementor elementor-19296 elementor-4173\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c858301 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"c858301\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;wave-brush&quot;}\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 283.5 27.8\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M283.5,9.7c0,0-7.3,4.3-14,4.6c-6.8,0.3-12.6,0-20.9-1.5c-11.3-2-33.1-10.1-44.7-5.7\ts-12.1,4.6-18,7.4c-6.6,3.2-20,9.6-36.6,9.3C131.6,23.5,99.5,7.2,86.3,8c-1.4,0.1-6.6,0.8-10.5,2c-3.8,1.2-9.4,3.8-17,4.7\tc-3.2,0.4-8.3,1.1-14.2,0.9c-1.5-0.1-6.3-0.4-12-1.6c-5.7-1.2-11-3.1-15.8-3.7C6.5,9.2,0,10.8,0,10.8V0h283.5V9.7z M260.8,11.3\tc-0.7-1-2-0.4-4.3-0.4c-2.3,0-6.1-1.2-5.8-1.1c0.3,0.1,3.1,1.5,6,1.9C259.7,12.2,261.4,12.3,260.8,11.3z M242.4,8.6\tc0,0-2.4-0.2-5.6-0.9c-3.2-0.8-10.3-2.8-15.1-3.5c-8.2-1.1-15.8,0-15.1,0.1c0.8,0.1,9.6-0.6,17.6,1.1c3.3,0.7,9.3,2.2,12.4,2.7\tC239.9,8.7,242.4,8.6,242.4,8.6z M185.2,8.5c1.7-0.7-13.3,4.7-18.5,6.1c-2.1,0.6-6.2,1.6-10,2c-3.9,0.4-8.9,0.4-8.8,0.5\tc0,0.2,5.8,0.8,11.2,0c5.4-0.8,5.2-1.1,7.6-1.6C170.5,14.7,183.5,9.2,185.2,8.5z M199.1,6.9c0.2,0-0.8-0.4-4.8,1.1\tc-4,1.5-6.7,3.5-6.9,3.7c-0.2,0.1,3.5-1.8,6.6-3C197,7.5,199,6.9,199.1,6.9z M283,6c-0.1,0.1-1.9,1.1-4.8,2.5s-6.9,2.8-6.7,2.7\tc0.2,0,3.5-0.6,7.4-2.5C282.8,6.8,283.1,5.9,283,6z M31.3,11.6c0.1-0.2-1.9-0.2-4.5-1.2s-5.4-1.6-7.8-2C15,7.6,7.3,8.5,7.7,8.6\tC8,8.7,15.9,8.3,20.2,9.3c2.2,0.5,2.4,0.5,5.7,1.6S31.2,11.9,31.3,11.6z M73,9.2c0.4-0.1,3.5-1.6,8.4-2.6c4.9-1.1,8.9-0.5,8.9-0.8\tc0-0.3-1-0.9-6.2-0.3S72.6,9.3,73,9.2z M71.6,6.7C71.8,6.8,75,5.4,77.3,5c2.3-0.3,1.9-0.5,1.9-0.6c0-0.1-1.1-0.2-2.7,0.2\tC74.8,5.1,71.4,6.6,71.6,6.7z M93.6,4.4c0.1,0.2,3.5,0.8,5.6,1.8c2.1,1,1.8,0.6,1.9,0.5c0.1-0.1-0.8-0.8-2.4-1.3\tC97.1,4.8,93.5,4.2,93.6,4.4z M65.4,11.1c-0.1,0.3,0.3,0.5,1.9-0.2s2.6-1.3,2.2-1.2s-0.9,0.4-2.5,0.8C65.3,10.9,65.5,10.8,65.4,11.1\tz M34.5,12.4c-0.2,0,2.1,0.8,3.3,0.9c1.2,0.1,2,0.1,2-0.2c0-0.3-0.1-0.5-1.6-0.4C36.6,12.8,34.7,12.4,34.5,12.4z M152.2,21.1\tc-0.1,0.1-2.4-0.3-7.5-0.3c-5,0-13.6-2.4-17.2-3.5c-3.6-1.1,10,3.9,16.5,4.1C150.5,21.6,152.3,21,152.2,21.1z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M269.6,18c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC267.7,18.8,269.7,18,269.6,18z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M227.4,9.8c-0.2-0.1-4.5-1-9.5-1.2c-5-0.2-12.7,0.6-12.3,0.5c0.3-0.1,5.9-1.8,13.3-1.2\tS227.6,9.9,227.4,9.8z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M204.5,13.4c-0.1-0.1,2-1,3.2-1.1c1.2-0.1,2,0,2,0.3c0,0.3-0.1,0.5-1.6,0.4\tC206.4,12.9,204.6,13.5,204.5,13.4z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M201,10.6c0-0.1-4.4,1.2-6.3,2.2c-1.9,0.9-6.2,3.1-6.1,3.1c0.1,0.1,4.2-1.6,6.3-2.6\tS201,10.7,201,10.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M154.5,26.7c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC152.6,27.5,154.6,26.8,154.5,26.7z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M41.9,19.3c0,0,1.2-0.3,2.9-0.1c1.7,0.2,5.8,0.9,8.2,0.7c4.2-0.4,7.4-2.7,7-2.6\tc-0.4,0-4.3,2.2-8.6,1.9c-1.8-0.1-5.1-0.5-6.7-0.4S41.9,19.3,41.9,19.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M75.5,12.6c0.2,0.1,2-0.8,4.3-1.1c2.3-0.2,2.1-0.3,2.1-0.5c0-0.1-1.8-0.4-3.4,0\tC76.9,11.5,75.3,12.5,75.5,12.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M15.6,13.2c0-0.1,4.3,0,6.7,0.5c2.4,0.5,5,1.9,5,2c0,0.1-2.7-0.8-5.1-1.4\tC19.9,13.7,15.7,13.3,15.6,13.2z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64ad365 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"64ad365\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-646316c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"646316c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-363e714 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"363e714\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f88761 elementor-widget elementor-widget-image\" data-id=\"8f88761\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"158\" height=\"90\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/icon-wave-l.webp\" class=\"attachment-large size-large wp-image-17925\" alt=\"icoen vagues jaunes\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ce41bf elementor-widget elementor-widget-heading\" data-id=\"9ce41bf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Excursi\u00f3n en canoa<br>VITRAC<span style=\"font-weight:200\"> castelnaud<\/span><br>VALLE DE LOS DOS CASTILLOS<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e85a1b elementor-widget elementor-widget-text-editor\" data-id=\"3e85a1b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Explore la ruta entre Vitrac y Castelnaud y disfrute de una experiencia inolvidable a lo largo de la Dordo\u00f1a.<\/p><p>Reme entre los pintorescos paisajes de la regi\u00f3n y emp\u00e1pese de la historia y la belleza natural que le rodea. \u00a1Le espera una emocionante aventura con Canoe Loisirs!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-766b364 elementor-widget elementor-widget-premium-addon-image-button\" data-id=\"766b364\" data-element_type=\"widget\" data-widget_type=\"premium-addon-image-button.default\">\n\t\t\t\t\t\n\t\t<a class=\"premium-image-button-none premium-image-button premium-btn-lg premium-image-button-none\" href=\"https:\/\/canoesloisirs.ats-sarlat.com:8443\/cgi-bin\/ProgATS\/eCommerce?licence=24CANOES_LOIS02&#038;lg=EN&#038;prest=VITCAST\" target=\"_blank\" rel=\"noopener\">\n\t\t\t<div class=\"premium-image-button-text-icon-wrapper\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\treservar ahora\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/a>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a6362bd e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"a6362bd\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64275f5 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"64275f5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-449add2 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"449add2\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d8401ac e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"d8401ac\" data-element_type=\"container\" id=\"who-we-are\">\n\t\t<div class=\"elementor-element elementor-element-684c2a8 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"684c2a8\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4b2e7b5 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"4b2e7b5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2cee0e0 elementor-widget elementor-widget-counter\" data-id=\"2cee0e0\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">descenso<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"12\" data-from-value=\"12\" data-delimiter=\",\">12<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"> km<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ec724d e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"5ec724d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a8929a3 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"a8929a3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f5c5d7 elementor-widget elementor-widget-counter\" data-id=\"4f5c5d7\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">a pasear<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">~ <\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"2\" data-from-value=\"2\" data-delimiter=\",\">2<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">h30<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-35a3d09 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"35a3d09\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1c60a78 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"1c60a78\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe6bc7a elementor-widget elementor-widget-image\" data-id=\"fe6bc7a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Falaise-de-vitrac-1024x683.jpeg\" class=\"attachment-large size-large wp-image-17981\" alt=\"Base de cano\u00eb \u00e0 Vitrac, Cano\u00ebs Loisirs devant les Falaises de Vitrac\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Falaise-de-vitrac-1024x683.jpeg 1024w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Falaise-de-vitrac-300x200.jpeg 300w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Falaise-de-vitrac-768x512.jpeg 768w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Falaise-de-vitrac-1536x1024.jpeg 1536w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Falaise-de-vitrac-600x400.jpeg 600w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Falaise-de-vitrac.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39af51b e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"39af51b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dbd9c63 elementor-widget elementor-widget-image\" data-id=\"dbd9c63\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9689-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-18281\" alt=\"\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9689-1-1024x683.jpg 1024w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9689-1-300x200.jpg 300w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9689-1-768x512.jpg 768w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9689-1-1536x1024.jpg 1536w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9689-1-2048x1365.jpg 2048w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9689-1-600x400.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e414d9 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"2e414d9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-032fd9e elementor-widget elementor-widget-image\" data-id=\"032fd9e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9900-1024x683.jpg\" class=\"attachment-large size-large wp-image-18285\" alt=\"Couple sur la plage de galet devant la Roque Gageac en Dordogne - Balade Cano\u00ebs Loisirs\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9900-1024x683.jpg 1024w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9900-300x200.jpg 300w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9900-768x512.jpg 768w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9900-1536x1024.jpg 1536w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9900-2048x1365.jpg 2048w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9900-600x400.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4baa0ac e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"4baa0ac\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-00018a9 elementor-widget elementor-widget-image\" data-id=\"00018a9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0323-1024x683.jpg\" class=\"attachment-large size-large wp-image-18069\" alt=\"cano\u00eb jaune sur la dordogne devant Castelnaud-la-Chapelle\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0323-1024x683.jpg 1024w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0323-300x200.jpg 300w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0323-768x512.jpg 768w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0323-1536x1024.jpg 1536w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0323-2048x1365.jpg 2048w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0323-600x400.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d4edc99 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"d4edc99\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-56655f1 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"56655f1\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9095f02 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"9095f02\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1d9e07b e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"1d9e07b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-625659d elementor-widget elementor-widget-image\" data-id=\"625659d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"178\" height=\"91\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2021\/10\/waves-small.png\" class=\"attachment-large size-large wp-image-17113\" alt=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3da5ac8 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"3da5ac8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 14px;font-weight: 500;color : black\">Canoa castelnaud<\/span><br>Descubre <span style=\"font-weight:700\">los tesoros<\/span> del <span style=\"font-weight:700\">valle de los 2 castillos<\/span> <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b23f61d elementor-widget elementor-widget-text-editor\" data-id=\"b23f61d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>La ruta en canoa Vitrac &#8211; Castelnaud es una <strong>una experiencia inolvidable<\/strong> que le permitir\u00e1 descubrir la belleza del r\u00edo Dordo\u00f1a desde una nueva perspectiva.<br>Esta ruta es <strong>imprescindible<\/strong> para los amantes de la naturaleza y los exploradores. Con 12 kil\u00f3metros de longitud, le llevar\u00e1 <strong>a trav\u00e9s de los paisajes m\u00e1s bellos del valle del Dordo\u00f1a<\/strong>. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a87a0a6 e-con-full elementor-hidden-mobile e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"a87a0a6\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44c494e e-transform elementor-widget elementor-widget-image\" data-id=\"44c494e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2300\" height=\"1533\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9981.webp\" class=\"attachment-full size-full wp-image-18289\" alt=\"Cano\u00eb La Roque Gageac sur la Dordogne devant La Roque Gageac - Cano\u00ebs Loisirs\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79cddf2 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"79cddf2\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2fd8bf4 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"2fd8bf4\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-78a691c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"78a691c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-903d298 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"903d298\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d20cf6 eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"5d20cf6\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <i aria-hidden=\"true\" class=\"icon icon-map-marker1\"><\/i>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">Encuentro en la base de Canoe Loisirs en el puerto de Vitrac. <\/h3>            <\/div>\n            <div><p>Aparque el coche y <strong>s\u00fabase<\/strong> a su canoa en <strong>10 minutos<\/strong>.<\/p><\/div>        <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7b04a96 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"7b04a96\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69af489 eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"69af489\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <i aria-hidden=\"true\" class=\"icon icon-clock11\"><\/i>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">Reservar una hora para nuestra organizaci\u00f3n<\/h3>            <\/div>\n            <div><p><strong>Salidas<\/strong> continuas de <strong>9.30 a 15.00 horas<\/strong>. <strong>Elige una hora de<\/strong> salida para ayudar a<strong>organizar<\/strong> el Equipo Amarillo.<\/p><\/div>        <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-10023a0 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"10023a0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7767341 eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"7767341\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <i aria-hidden=\"true\" class=\"icon icon-hourglass\"><\/i>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">Ruta sin estr\u00e9s<\/h3>            <\/div>\n            <div><p><strong>T\u00f3mese<\/strong> su tiempo para disfrutar al m\u00e1ximo de su descenso. T\u00f3mese un descanso para <strong>nadar<\/strong>, <strong>visitar un pueblo<\/strong> y hacer <strong>fotos<\/strong>. No te preocupes por <strong>dejar tu barca junto al r\u00edo<\/strong>.<\/p><\/div>        <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7b3bde3 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"7b3bde3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba038b6 eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"ba038b6\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <i aria-hidden=\"true\" class=\"icon icon-team\"><\/i>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">CONSEJOS DEL EQUIPO AMARILLO<\/h3>            <\/div>\n            <div><p>Antes de salir, un miembro de <strong>nuestro<\/strong> equipo se reunir\u00e1 con usted y le<strong> explicar\u00e1 todo<\/strong> sobre su ruta y c\u00f3mo dirigir una canoa.<\/p><\/div>        <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c9539d e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"2c9539d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a527886 eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"a527886\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <i aria-hidden=\"true\" class=\"icon icon-bus\"><\/i>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">TRANSPORTE DE VUELTA<\/h3>            <\/div>\n            <div><p>Tras el descenso, un <strong>autob\u00fas<\/strong> te llevar\u00e1 de vuelta al punto de partida.<br>Los autobuses salen continuamente cada hora (seg\u00fan la temporada; m\u00e1s informaci\u00f3n disponible en el sitio antes de tu salida).<\/p><\/div>        <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-508413e e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"508413e\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ed50fed e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"ed50fed\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-aad04f0 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"aad04f0\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d2b8a12 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"d2b8a12\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1147e4d elementor-widget elementor-widget-counter\" data-id=\"1147e4d\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">por adulto<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"21\" data-from-value=\"21\" data-delimiter=\",\">21<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">\u20ac<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05dc5d8 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"05dc5d8\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-aafa337 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"aafa337\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e86d948 elementor-widget elementor-widget-counter\" data-id=\"e86d948\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">pirag\u00fcismo para ni\u00f1os de 5 a 12 a\u00f1os<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"12.5\" data-from-value=\"12.5\" data-delimiter=\",\">12.5<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">\u20ac<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eed5f95 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"eed5f95\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f794afe e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"f794afe\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4266b8b elementor-widget elementor-widget-counter\" data-id=\"4266b8b\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Kayak para adultos o ni\u00f1os<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"25\" data-from-value=\"25\" data-delimiter=\",\">25<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">\u20ac<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e443144 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"e443144\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;wave-brush&quot;,&quot;shape_divider_bottom&quot;:&quot;wave-brush&quot;}\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 283.5 27.8\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M283.5,9.7c0,0-7.3,4.3-14,4.6c-6.8,0.3-12.6,0-20.9-1.5c-11.3-2-33.1-10.1-44.7-5.7\ts-12.1,4.6-18,7.4c-6.6,3.2-20,9.6-36.6,9.3C131.6,23.5,99.5,7.2,86.3,8c-1.4,0.1-6.6,0.8-10.5,2c-3.8,1.2-9.4,3.8-17,4.7\tc-3.2,0.4-8.3,1.1-14.2,0.9c-1.5-0.1-6.3-0.4-12-1.6c-5.7-1.2-11-3.1-15.8-3.7C6.5,9.2,0,10.8,0,10.8V0h283.5V9.7z M260.8,11.3\tc-0.7-1-2-0.4-4.3-0.4c-2.3,0-6.1-1.2-5.8-1.1c0.3,0.1,3.1,1.5,6,1.9C259.7,12.2,261.4,12.3,260.8,11.3z M242.4,8.6\tc0,0-2.4-0.2-5.6-0.9c-3.2-0.8-10.3-2.8-15.1-3.5c-8.2-1.1-15.8,0-15.1,0.1c0.8,0.1,9.6-0.6,17.6,1.1c3.3,0.7,9.3,2.2,12.4,2.7\tC239.9,8.7,242.4,8.6,242.4,8.6z M185.2,8.5c1.7-0.7-13.3,4.7-18.5,6.1c-2.1,0.6-6.2,1.6-10,2c-3.9,0.4-8.9,0.4-8.8,0.5\tc0,0.2,5.8,0.8,11.2,0c5.4-0.8,5.2-1.1,7.6-1.6C170.5,14.7,183.5,9.2,185.2,8.5z M199.1,6.9c0.2,0-0.8-0.4-4.8,1.1\tc-4,1.5-6.7,3.5-6.9,3.7c-0.2,0.1,3.5-1.8,6.6-3C197,7.5,199,6.9,199.1,6.9z M283,6c-0.1,0.1-1.9,1.1-4.8,2.5s-6.9,2.8-6.7,2.7\tc0.2,0,3.5-0.6,7.4-2.5C282.8,6.8,283.1,5.9,283,6z M31.3,11.6c0.1-0.2-1.9-0.2-4.5-1.2s-5.4-1.6-7.8-2C15,7.6,7.3,8.5,7.7,8.6\tC8,8.7,15.9,8.3,20.2,9.3c2.2,0.5,2.4,0.5,5.7,1.6S31.2,11.9,31.3,11.6z M73,9.2c0.4-0.1,3.5-1.6,8.4-2.6c4.9-1.1,8.9-0.5,8.9-0.8\tc0-0.3-1-0.9-6.2-0.3S72.6,9.3,73,9.2z M71.6,6.7C71.8,6.8,75,5.4,77.3,5c2.3-0.3,1.9-0.5,1.9-0.6c0-0.1-1.1-0.2-2.7,0.2\tC74.8,5.1,71.4,6.6,71.6,6.7z M93.6,4.4c0.1,0.2,3.5,0.8,5.6,1.8c2.1,1,1.8,0.6,1.9,0.5c0.1-0.1-0.8-0.8-2.4-1.3\tC97.1,4.8,93.5,4.2,93.6,4.4z M65.4,11.1c-0.1,0.3,0.3,0.5,1.9-0.2s2.6-1.3,2.2-1.2s-0.9,0.4-2.5,0.8C65.3,10.9,65.5,10.8,65.4,11.1\tz M34.5,12.4c-0.2,0,2.1,0.8,3.3,0.9c1.2,0.1,2,0.1,2-0.2c0-0.3-0.1-0.5-1.6-0.4C36.6,12.8,34.7,12.4,34.5,12.4z M152.2,21.1\tc-0.1,0.1-2.4-0.3-7.5-0.3c-5,0-13.6-2.4-17.2-3.5c-3.6-1.1,10,3.9,16.5,4.1C150.5,21.6,152.3,21,152.2,21.1z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M269.6,18c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC267.7,18.8,269.7,18,269.6,18z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M227.4,9.8c-0.2-0.1-4.5-1-9.5-1.2c-5-0.2-12.7,0.6-12.3,0.5c0.3-0.1,5.9-1.8,13.3-1.2\tS227.6,9.9,227.4,9.8z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M204.5,13.4c-0.1-0.1,2-1,3.2-1.1c1.2-0.1,2,0,2,0.3c0,0.3-0.1,0.5-1.6,0.4\tC206.4,12.9,204.6,13.5,204.5,13.4z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M201,10.6c0-0.1-4.4,1.2-6.3,2.2c-1.9,0.9-6.2,3.1-6.1,3.1c0.1,0.1,4.2-1.6,6.3-2.6\tS201,10.7,201,10.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M154.5,26.7c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC152.6,27.5,154.6,26.8,154.5,26.7z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M41.9,19.3c0,0,1.2-0.3,2.9-0.1c1.7,0.2,5.8,0.9,8.2,0.7c4.2-0.4,7.4-2.7,7-2.6\tc-0.4,0-4.3,2.2-8.6,1.9c-1.8-0.1-5.1-0.5-6.7-0.4S41.9,19.3,41.9,19.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M75.5,12.6c0.2,0.1,2-0.8,4.3-1.1c2.3-0.2,2.1-0.3,2.1-0.5c0-0.1-1.8-0.4-3.4,0\tC76.9,11.5,75.3,12.5,75.5,12.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M15.6,13.2c0-0.1,4.3,0,6.7,0.5c2.4,0.5,5,1.9,5,2c0,0.1-2.7-0.8-5.1-1.4\tC19.9,13.7,15.7,13.3,15.6,13.2z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 283.5 27.8\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M283.5,9.7c0,0-7.3,4.3-14,4.6c-6.8,0.3-12.6,0-20.9-1.5c-11.3-2-33.1-10.1-44.7-5.7\ts-12.1,4.6-18,7.4c-6.6,3.2-20,9.6-36.6,9.3C131.6,23.5,99.5,7.2,86.3,8c-1.4,0.1-6.6,0.8-10.5,2c-3.8,1.2-9.4,3.8-17,4.7\tc-3.2,0.4-8.3,1.1-14.2,0.9c-1.5-0.1-6.3-0.4-12-1.6c-5.7-1.2-11-3.1-15.8-3.7C6.5,9.2,0,10.8,0,10.8V0h283.5V9.7z M260.8,11.3\tc-0.7-1-2-0.4-4.3-0.4c-2.3,0-6.1-1.2-5.8-1.1c0.3,0.1,3.1,1.5,6,1.9C259.7,12.2,261.4,12.3,260.8,11.3z M242.4,8.6\tc0,0-2.4-0.2-5.6-0.9c-3.2-0.8-10.3-2.8-15.1-3.5c-8.2-1.1-15.8,0-15.1,0.1c0.8,0.1,9.6-0.6,17.6,1.1c3.3,0.7,9.3,2.2,12.4,2.7\tC239.9,8.7,242.4,8.6,242.4,8.6z M185.2,8.5c1.7-0.7-13.3,4.7-18.5,6.1c-2.1,0.6-6.2,1.6-10,2c-3.9,0.4-8.9,0.4-8.8,0.5\tc0,0.2,5.8,0.8,11.2,0c5.4-0.8,5.2-1.1,7.6-1.6C170.5,14.7,183.5,9.2,185.2,8.5z M199.1,6.9c0.2,0-0.8-0.4-4.8,1.1\tc-4,1.5-6.7,3.5-6.9,3.7c-0.2,0.1,3.5-1.8,6.6-3C197,7.5,199,6.9,199.1,6.9z M283,6c-0.1,0.1-1.9,1.1-4.8,2.5s-6.9,2.8-6.7,2.7\tc0.2,0,3.5-0.6,7.4-2.5C282.8,6.8,283.1,5.9,283,6z M31.3,11.6c0.1-0.2-1.9-0.2-4.5-1.2s-5.4-1.6-7.8-2C15,7.6,7.3,8.5,7.7,8.6\tC8,8.7,15.9,8.3,20.2,9.3c2.2,0.5,2.4,0.5,5.7,1.6S31.2,11.9,31.3,11.6z M73,9.2c0.4-0.1,3.5-1.6,8.4-2.6c4.9-1.1,8.9-0.5,8.9-0.8\tc0-0.3-1-0.9-6.2-0.3S72.6,9.3,73,9.2z M71.6,6.7C71.8,6.8,75,5.4,77.3,5c2.3-0.3,1.9-0.5,1.9-0.6c0-0.1-1.1-0.2-2.7,0.2\tC74.8,5.1,71.4,6.6,71.6,6.7z M93.6,4.4c0.1,0.2,3.5,0.8,5.6,1.8c2.1,1,1.8,0.6,1.9,0.5c0.1-0.1-0.8-0.8-2.4-1.3\tC97.1,4.8,93.5,4.2,93.6,4.4z M65.4,11.1c-0.1,0.3,0.3,0.5,1.9-0.2s2.6-1.3,2.2-1.2s-0.9,0.4-2.5,0.8C65.3,10.9,65.5,10.8,65.4,11.1\tz M34.5,12.4c-0.2,0,2.1,0.8,3.3,0.9c1.2,0.1,2,0.1,2-0.2c0-0.3-0.1-0.5-1.6-0.4C36.6,12.8,34.7,12.4,34.5,12.4z M152.2,21.1\tc-0.1,0.1-2.4-0.3-7.5-0.3c-5,0-13.6-2.4-17.2-3.5c-3.6-1.1,10,3.9,16.5,4.1C150.5,21.6,152.3,21,152.2,21.1z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M269.6,18c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC267.7,18.8,269.7,18,269.6,18z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M227.4,9.8c-0.2-0.1-4.5-1-9.5-1.2c-5-0.2-12.7,0.6-12.3,0.5c0.3-0.1,5.9-1.8,13.3-1.2\tS227.6,9.9,227.4,9.8z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M204.5,13.4c-0.1-0.1,2-1,3.2-1.1c1.2-0.1,2,0,2,0.3c0,0.3-0.1,0.5-1.6,0.4\tC206.4,12.9,204.6,13.5,204.5,13.4z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M201,10.6c0-0.1-4.4,1.2-6.3,2.2c-1.9,0.9-6.2,3.1-6.1,3.1c0.1,0.1,4.2-1.6,6.3-2.6\tS201,10.7,201,10.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M154.5,26.7c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC152.6,27.5,154.6,26.8,154.5,26.7z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M41.9,19.3c0,0,1.2-0.3,2.9-0.1c1.7,0.2,5.8,0.9,8.2,0.7c4.2-0.4,7.4-2.7,7-2.6\tc-0.4,0-4.3,2.2-8.6,1.9c-1.8-0.1-5.1-0.5-6.7-0.4S41.9,19.3,41.9,19.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M75.5,12.6c0.2,0.1,2-0.8,4.3-1.1c2.3-0.2,2.1-0.3,2.1-0.5c0-0.1-1.8-0.4-3.4,0\tC76.9,11.5,75.3,12.5,75.5,12.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M15.6,13.2c0-0.1,4.3,0,6.7,0.5c2.4,0.5,5,1.9,5,2c0,0.1-2.7-0.8-5.1-1.4\tC19.9,13.7,15.7,13.3,15.6,13.2z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-672d694 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"672d694\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4757c47 wpr-lottie-svg elementor-widget elementor-widget-wpr-lottie-animations\" data-id=\"4757c47\" data-element_type=\"widget\" data-settings=\"{&quot;json_file&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/canoes-loisirs.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/data_vitrac-castelnaud_ok.json&quot;,&quot;id&quot;:23728,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;trigger&quot;:&quot;none&quot;}\" data-widget_type=\"wpr-lottie-animations.default\">\n\t\t\t\t\t<div class=\"wpr-lottie-animations-wrapper\"><div class=\"wpr-lottie-animations\" data-settings=\"{&quot;loop&quot;:&quot;yes&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;speed&quot;:1,&quot;trigger&quot;:&quot;none&quot;,&quot;reverse&quot;:&quot;&quot;,&quot;scroll_start&quot;:&quot;0&quot;,&quot;scroll_end&quot;:&quot;100&quot;,&quot;lottie_renderer&quot;:&quot;svg&quot;}\" data-json-url=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/12\/data_vitrac-castelnaud_ok.json\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c50efa2 e-con-full elementor-hidden-desktop e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"c50efa2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12ea403 wpr-lottie-svg elementor-widget elementor-widget-wpr-lottie-animations\" data-id=\"12ea403\" data-element_type=\"widget\" data-settings=\"{&quot;json_file&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/canoes-loisirs.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/data_vitrac-castelnaud-xs-ok.json&quot;,&quot;id&quot;:23811,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;trigger&quot;:&quot;none&quot;}\" data-widget_type=\"wpr-lottie-animations.default\">\n\t\t\t\t\t<div class=\"wpr-lottie-animations-wrapper\"><div class=\"wpr-lottie-animations\" data-settings=\"{&quot;loop&quot;:&quot;yes&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;speed&quot;:1,&quot;trigger&quot;:&quot;none&quot;,&quot;reverse&quot;:&quot;&quot;,&quot;scroll_start&quot;:&quot;0&quot;,&quot;scroll_end&quot;:&quot;100&quot;,&quot;lottie_renderer&quot;:&quot;svg&quot;}\" data-json-url=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/12\/data_vitrac-castelnaud-xs-ok.json\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39e9310 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"39e9310\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ca2508d e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"ca2508d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ba1a16 elementor-widget elementor-widget-image\" data-id=\"9ba1a16\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"256\" height=\"256\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2022\/12\/payjmpng.png\" class=\"attachment-large size-large wp-image-17689\" alt=\"\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2022\/12\/payjmpng.png 256w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2022\/12\/payjmpng-150x150.png 150w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2022\/12\/payjmpng-100x100.png 100w\" sizes=\"(max-width: 256px) 100vw, 256px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-054070b elementor-widget elementor-widget-heading\" data-id=\"054070b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 14px;font-weight: 500;color : black\">Excursi\u00f3n en canoa por Castelnaud<\/span><br><span style=\"font-weight:300;color:black!important\">Programa de la excursi\u00f3n<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05f7f73 elementor-widget elementor-widget-text-editor\" data-id=\"05f7f73\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nos vemos en nuestra base de canoas en Vitrac.<br>Se proporcionar\u00e1 equipo (<span style=\"font-family: inherit; color: var( --e-global-color-text ); letter-spacing: -0.011em;\">canoas, chalecos salvavidas, remos, bolsas impermeables<\/span>), y consejos de seguridad.<\/p><p><span style=\"font-weight: 600;\">Traslado en autob\u00fas al punto de partida:<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6c1817 wpr-list-style-none elementor-widget elementor-widget-wpr-posts-timeline\" data-id=\"f6c1817\" data-element_type=\"widget\" data-settings=\"{&quot;animation_offset&quot;:150,&quot;aos_animation_duration&quot;:600}\" data-widget_type=\"wpr-posts-timeline.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-wrapper wpr-vertical wpr-centered\">\n\t\t\t<div class=\"wpr-timeline-centered wpr-line wpr-both-sided-timeline\"><div class=\"wpr-middle-line\"><\/div><div class=\"wpr-timeline-fill\" data-layout=\"centered\"><\/div><span class=\"wpr-year-wrap\"><span class=\"wpr-year-label wpr-year\">Salida<\/span><\/span><article class=\"wpr-timeline-entry wpr-left-aligned elementor-repeater-item-7fd00c2\" data-item-id=\"elementor-repeater-item-7fd00c2\"><time class=\"wpr-extra-label\" data-aos=\"fade\" data-aos-left=\"\" data-aos-right=\"\" data-animation-offset=\"150\" data-animation-duration=\"600\"><span class=\"wpr-label\">Base de Cano\u00ebs Loisirs<\/span><\/time><div class=\"wpr-timeline-entry-inner\"><div class=\"wpr-main-line-icon wpr-icon\"><i aria-hidden=\"true\" class=\"far fa-flag\"><\/i><\/div><div class=\"wpr-story-info-vertical wpr-data-wrap \"  data-aos=\"fade\" data-aos-left=\"\" data-aos-right=\"\" data-animation-offset=\"150\" data-animation-duration=\"600\"><div class=\"wpr-animation-wrap wpr-timeline-media\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9242-2048x1365.webp\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"Deux personnes qui vont embarquer dans un cano\u00ebs de Cano\u00ebs Loisirs \u00e0 Vitrac - Cano\u00ebs Loisirs\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9242.webp 1920w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9242-300x200.webp 300w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9242-1024x683.webp 1024w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9242-768x512.webp 768w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9242-1536x1024.webp 1536w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9242-600x400.webp 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><div class=\"wpr-timeline-story-overlay \"><div class=\"wpr-title-wrap\"><span class=\"wpr-title\">Salida de Vitrac<\/span><\/div><\/div><\/div><div class=\"wpr-timeline-content-wrapper\"><div class=\"wpr-content-wrapper\"><div class=\"wpr-description\"><p>\u00bfEst\u00e1 preparado para una aventura inolvidable?<\/p><p>Comience su viaje desde nuestro punto de partida en Vitrac y d\u00e9jese hechizar por la belleza natural de la Dordo\u00f1a. Tanto si es un principiante como un experto pirag\u00fcista, nuestro equipo est\u00e1 aqu\u00ed para ayudarle a disfrutar de momentos de puro placer y descubrimiento. Prep\u00e1rese para crear recuerdos inolvidables con Canoe Loisirs.<\/p><\/div><\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/article><span class=\"wpr-year-wrap\"><span class=\"wpr-year-label wpr-year\">3 km<\/span><\/span><article class=\"wpr-timeline-entry wpr-right-aligned elementor-repeater-item-20c3cbe\" data-item-id=\"elementor-repeater-item-20c3cbe\"><time class=\"wpr-extra-label\" data-aos=\"fade\" data-aos-left=\"\" data-aos-right=\"\" data-animation-offset=\"150\" data-animation-duration=\"600\"><span class=\"wpr-label\">La Bastida de Domme<\/span><\/time><div class=\"wpr-timeline-entry-inner\"><div class=\"wpr-main-line-icon wpr-icon\"><i aria-hidden=\"true\" class=\"far fa-flag\"><\/i><\/div><div class=\"wpr-story-info-vertical wpr-data-wrap \"  data-aos=\"fade\" data-aos-left=\"\" data-aos-right=\"\" data-animation-offset=\"150\" data-animation-duration=\"600\"><div class=\"wpr-animation-wrap wpr-timeline-media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"770\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/4854_village_de_domme_\u00a9-Declic-Decolle_expiresOn-2026-12-01-1024x770.webp\" class=\"attachment-large size-large\" alt=\"Bastide de Domme vue du ciel surplombant la Dordogne - Cano\u00ebs Loisirs\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/4854_village_de_domme_\u00a9-Declic-Decolle_expiresOn-2026-12-01-1024x770.webp 1024w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/4854_village_de_domme_\u00a9-Declic-Decolle_expiresOn-2026-12-01-300x225.webp 300w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/4854_village_de_domme_\u00a9-Declic-Decolle_expiresOn-2026-12-01-768x577.webp 768w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/4854_village_de_domme_\u00a9-Declic-Decolle_expiresOn-2026-12-01-1536x1154.webp 1536w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/4854_village_de_domme_\u00a9-Declic-Decolle_expiresOn-2026-12-01.webp 1920w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/4854_village_de_domme_\u00a9-Declic-Decolle_expiresOn-2026-12-01-600x451.webp 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><div class=\"wpr-timeline-story-overlay \"><\/div><\/div><div class=\"wpr-timeline-content-wrapper\"><div class=\"wpr-content-wrapper\"><div class=\"wpr-description\"><p>Descubra la belleza intemporal de Domme desde la comodidad de su canoa. Encaramado en un acantilado con vistas a la Dordo\u00f1a, este pueblo medieval ofrece panoramas impresionantes que son realmente \u00fanicos. Reme a lo largo de sus murallas y d\u00e9jese seducir por su encanto hist\u00f3rico.<\/p><\/div><\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/article><span class=\"wpr-year-wrap\"><span class=\"wpr-year-label wpr-year\">7,3 km<\/span><\/span><article class=\"wpr-timeline-entry wpr-left-aligned elementor-repeater-item-392ce15\" data-item-id=\"elementor-repeater-item-392ce15\"><time class=\"wpr-extra-label\" data-aos=\"fade\" data-aos-left=\"\" data-aos-right=\"\" data-animation-offset=\"150\" data-animation-duration=\"600\"><span class=\"wpr-label\">La Roque-Gajeac<\/span><\/time><div class=\"wpr-timeline-entry-inner\"><div class=\"wpr-main-line-icon wpr-icon\"><i aria-hidden=\"true\" class=\"far fa-flag\"><\/i><\/div><div class=\"wpr-story-info-vertical wpr-data-wrap \"  data-aos=\"fade\" data-aos-left=\"\" data-aos-right=\"\" data-animation-offset=\"150\" data-animation-duration=\"600\"><div class=\"wpr-animation-wrap wpr-timeline-media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9897-1024x683.webp\" class=\"attachment-large size-large\" alt=\"Couple \u00e0 c\u00f4t\u00e9 de leur cano\u00eb jaune devant la Roque Gageac\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9897-1024x683.webp 1024w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9897-300x200.webp 300w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9897-768x512.webp 768w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9897-1536x1024.webp 1536w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9897.webp 1920w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9897-600x400.webp 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><div class=\"wpr-timeline-story-overlay \"><\/div><\/div><div class=\"wpr-timeline-content-wrapper\"><div class=\"wpr-content-wrapper\"><div class=\"wpr-description\"><p>\u00a1Explore la historia desde su canoa en La Roque-Gageac! Este pueblo troglodita encaramado a orillas del Dordo\u00f1a ofrece unas vistas impresionantes desde el agua. Desl\u00edcese entre sus pintorescas casas y contemple los acantilados que la dominan.<\/p><\/div><\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/article><span class=\"wpr-year-wrap\"><span class=\"wpr-year-label wpr-year\">7,8 km<\/span><\/span><article class=\"wpr-timeline-entry wpr-right-aligned elementor-repeater-item-7f5d981\" data-item-id=\"elementor-repeater-item-7f5d981\"><time class=\"wpr-extra-label\" data-aos=\"fade\" data-aos-left=\"\" data-aos-right=\"\" data-animation-offset=\"150\" data-animation-duration=\"600\"><span class=\"wpr-label\">Castillo de la Malartrie<\/span><\/time><div class=\"wpr-timeline-entry-inner\"><div class=\"wpr-main-line-icon wpr-icon\"><i aria-hidden=\"true\" class=\"far fa-flag\"><\/i><\/div><div class=\"wpr-story-info-vertical wpr-data-wrap \"  data-aos=\"fade\" data-aos-left=\"\" data-aos-right=\"\" data-animation-offset=\"150\" data-animation-duration=\"600\"><div class=\"wpr-animation-wrap wpr-timeline-media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0005-1-1024x683.webp\" class=\"attachment-large size-large\" alt=\"Balade cano\u00ebs devant le ch\u00e2teau de Malartrie \u00e0 la Roque-Gajeac - Cano\u00ebs Loisirs\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0005-1-1024x683.webp 1024w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0005-1-300x200.webp 300w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0005-1-768x512.webp 768w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0005-1-1536x1024.webp 1536w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0005-1.webp 1920w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0005-1-600x400.webp 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><div class=\"wpr-timeline-story-overlay \"><\/div><\/div><div class=\"wpr-timeline-content-wrapper\"><div class=\"wpr-content-wrapper\"><div class=\"wpr-description\"><p>\u00a1Contemple el Castillo de la Malartrie desde su canoa! Enclavado a orillas del Dordo\u00f1a, este castillo ofrece una vista majestuosa desde el agua. Reme tranquilamente mientras admira su elegante arquitectura y su encantador entorno natural.<\/p><\/div><\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/article><span class=\"wpr-year-wrap\"><span class=\"wpr-year-label wpr-year\">Llegada<\/span><\/span><article class=\"wpr-timeline-entry wpr-left-aligned elementor-repeater-item-0896ada\" data-item-id=\"elementor-repeater-item-0896ada\"><time class=\"wpr-extra-label\" data-aos=\"fade\" data-aos-left=\"\" data-aos-right=\"\" data-animation-offset=\"150\" data-animation-duration=\"600\"><span class=\"wpr-label\">Castelnaud-la-Chapelle<\/span><\/time><div class=\"wpr-timeline-entry-inner\"><div class=\"wpr-main-line-icon wpr-icon\"><i aria-hidden=\"true\" class=\"far fa-flag\"><\/i><\/div><div class=\"wpr-story-info-vertical wpr-data-wrap \"  data-aos=\"fade\" data-aos-left=\"\" data-aos-right=\"\" data-animation-offset=\"150\" data-animation-duration=\"600\"><div class=\"wpr-animation-wrap wpr-timeline-media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0323-1024x683.webp\" class=\"attachment-large size-large\" alt=\"cano\u00eb jaune sur la dordogne devant Castelnaud-la-Chapelle\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0323-1024x683.webp 1024w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0323-300x200.webp 300w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0323-768x512.webp 768w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0323-1536x1024.webp 1536w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0323.webp 1920w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0323-600x400.webp 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><div class=\"wpr-timeline-story-overlay \"><\/div><\/div><div class=\"wpr-timeline-content-wrapper\"><div class=\"wpr-content-wrapper\"><div class=\"wpr-description\"><p>Su llegada a Castelnaud es un momento emocionante. Una vez desembarcado, ser\u00e1 recibido por las majestuosas torres del castillo medieval, que se yerguen orgullosas sobre la Dordo\u00f1a. Nuestra lanzadera le recoger\u00e1 y le llevar\u00e1 de vuelta a la base de Vitrac.<\/p><\/div><\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/article><\/div>    \n\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ecc2f94 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"ecc2f94\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4a64ff9 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"4a64ff9\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-48be89d e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"48be89d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-92c5492 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"92c5492\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3cac5fc elementor-widget elementor-widget-image\" data-id=\"3cac5fc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"178\" height=\"91\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2021\/10\/waves-small.png\" class=\"attachment-large size-large wp-image-17113\" alt=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6155b39 elementor-widget elementor-widget-heading\" data-id=\"6155b39\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AVENTURERO PERO NO REDENTOR<br><span style=\"font-weight:200\">ESPECIALMENTE BAJO LA LLUVIA<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3bb997 elementor-widget elementor-widget-text-editor\" data-id=\"e3bb997\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-transform: uppercase; font-size: 1.5rem;\">Opta por tu billete con fecha modificable<\/h4><p>Disfruta de un paseo bajo el hermoso sol de Dordo\u00f1a.<br><b>La \u00fanica regla: av\u00edsanos con 36 horas de antelaci\u00f3n<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a6bbda4 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"a6bbda4\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8e5a579 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"8e5a579\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8c7b7c elementor-widget elementor-widget-image\" data-id=\"c8c7b7c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/canoes-bivouac-1024x683.jpg\" class=\"attachment-large size-large wp-image-17865\" alt=\"deux cano\u00ebs jaunes cano\u00ebs Loisis devant une tente de camping au bord de la dordogne\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/canoes-bivouac-1024x683.jpg 1024w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/canoes-bivouac-300x200.jpg 300w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/canoes-bivouac-768x512.jpg 768w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/canoes-bivouac-600x400.jpg 600w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/canoes-bivouac.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c982671 elementor-widget elementor-widget-heading\" data-id=\"c982671\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ahorre tiempo <span style=\"font-weight:200\"> a su llegada<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b421856 elementor-widget elementor-widget-text-editor\" data-id=\"b421856\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Un miembro del Equipo Amarillo se har\u00e1 <strong>cargo de usted lo antes<\/strong> posible para <strong>minimizar el tiempo de espera<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e52d7f3 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"e52d7f3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-000132a elementor-widget elementor-widget-image\" data-id=\"000132a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9144-1-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-18385\" alt=\"Couple qui pagaie dans Cano\u00eb sur la dordogne devant Falaise de Vitrac\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9144-1-1-1024x683.jpg 1024w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9144-1-1-300x200.jpg 300w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9144-1-1-768x512.jpg 768w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9144-1-1-1536x1024.jpg 1536w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9144-1-1-2048x1365.jpg 2048w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.9144-1-1-600x400.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11585be elementor-widget elementor-widget-heading\" data-id=\"11585be\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-weight:200\"> Un<\/span> paseo al sol<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49ee16b elementor-widget elementor-widget-text-editor\" data-id=\"49ee16b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Cambie<\/strong> su fecha con hasta <strong>36 horas de antelaci\u00f3n<\/strong> para asegurarse un viaje soleado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d26344 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"7d26344\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17cdbc4 elementor-widget elementor-widget-image\" data-id=\"17cdbc4\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.8555-2-1024x683.jpg\" class=\"attachment-large size-large wp-image-18393\" alt=\"Cano\u00ebs jaunes Cano\u00ebs Loisirs devant la Falaise de Vitrac\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.8555-2-1024x683.jpg 1024w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.8555-2-300x200.jpg 300w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.8555-2-768x512.jpg 768w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.8555-2-1536x1024.jpg 1536w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.8555-2-2048x1365.jpg 2048w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.8555-2-600x400.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7eb8c42 elementor-widget elementor-widget-heading\" data-id=\"7eb8c42\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Garantizarse <span style=\"font-weight:200\"> una canoa<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3c01b3 elementor-widget elementor-widget-text-editor\" data-id=\"f3c01b3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>El Equipo Amarillo<strong> garantiza la disponibilidad<\/strong> de canoas para todos los <strong>titulares de un billete intercambiable<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-caa8279 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"caa8279\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;shape_divider_top&quot;:&quot;wave-brush&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 283.5 27.8\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M283.5,9.7c0,0-7.3,4.3-14,4.6c-6.8,0.3-12.6,0-20.9-1.5c-11.3-2-33.1-10.1-44.7-5.7\ts-12.1,4.6-18,7.4c-6.6,3.2-20,9.6-36.6,9.3C131.6,23.5,99.5,7.2,86.3,8c-1.4,0.1-6.6,0.8-10.5,2c-3.8,1.2-9.4,3.8-17,4.7\tc-3.2,0.4-8.3,1.1-14.2,0.9c-1.5-0.1-6.3-0.4-12-1.6c-5.7-1.2-11-3.1-15.8-3.7C6.5,9.2,0,10.8,0,10.8V0h283.5V9.7z M260.8,11.3\tc-0.7-1-2-0.4-4.3-0.4c-2.3,0-6.1-1.2-5.8-1.1c0.3,0.1,3.1,1.5,6,1.9C259.7,12.2,261.4,12.3,260.8,11.3z M242.4,8.6\tc0,0-2.4-0.2-5.6-0.9c-3.2-0.8-10.3-2.8-15.1-3.5c-8.2-1.1-15.8,0-15.1,0.1c0.8,0.1,9.6-0.6,17.6,1.1c3.3,0.7,9.3,2.2,12.4,2.7\tC239.9,8.7,242.4,8.6,242.4,8.6z M185.2,8.5c1.7-0.7-13.3,4.7-18.5,6.1c-2.1,0.6-6.2,1.6-10,2c-3.9,0.4-8.9,0.4-8.8,0.5\tc0,0.2,5.8,0.8,11.2,0c5.4-0.8,5.2-1.1,7.6-1.6C170.5,14.7,183.5,9.2,185.2,8.5z M199.1,6.9c0.2,0-0.8-0.4-4.8,1.1\tc-4,1.5-6.7,3.5-6.9,3.7c-0.2,0.1,3.5-1.8,6.6-3C197,7.5,199,6.9,199.1,6.9z M283,6c-0.1,0.1-1.9,1.1-4.8,2.5s-6.9,2.8-6.7,2.7\tc0.2,0,3.5-0.6,7.4-2.5C282.8,6.8,283.1,5.9,283,6z M31.3,11.6c0.1-0.2-1.9-0.2-4.5-1.2s-5.4-1.6-7.8-2C15,7.6,7.3,8.5,7.7,8.6\tC8,8.7,15.9,8.3,20.2,9.3c2.2,0.5,2.4,0.5,5.7,1.6S31.2,11.9,31.3,11.6z M73,9.2c0.4-0.1,3.5-1.6,8.4-2.6c4.9-1.1,8.9-0.5,8.9-0.8\tc0-0.3-1-0.9-6.2-0.3S72.6,9.3,73,9.2z M71.6,6.7C71.8,6.8,75,5.4,77.3,5c2.3-0.3,1.9-0.5,1.9-0.6c0-0.1-1.1-0.2-2.7,0.2\tC74.8,5.1,71.4,6.6,71.6,6.7z M93.6,4.4c0.1,0.2,3.5,0.8,5.6,1.8c2.1,1,1.8,0.6,1.9,0.5c0.1-0.1-0.8-0.8-2.4-1.3\tC97.1,4.8,93.5,4.2,93.6,4.4z M65.4,11.1c-0.1,0.3,0.3,0.5,1.9-0.2s2.6-1.3,2.2-1.2s-0.9,0.4-2.5,0.8C65.3,10.9,65.5,10.8,65.4,11.1\tz M34.5,12.4c-0.2,0,2.1,0.8,3.3,0.9c1.2,0.1,2,0.1,2-0.2c0-0.3-0.1-0.5-1.6-0.4C36.6,12.8,34.7,12.4,34.5,12.4z M152.2,21.1\tc-0.1,0.1-2.4-0.3-7.5-0.3c-5,0-13.6-2.4-17.2-3.5c-3.6-1.1,10,3.9,16.5,4.1C150.5,21.6,152.3,21,152.2,21.1z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M269.6,18c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC267.7,18.8,269.7,18,269.6,18z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M227.4,9.8c-0.2-0.1-4.5-1-9.5-1.2c-5-0.2-12.7,0.6-12.3,0.5c0.3-0.1,5.9-1.8,13.3-1.2\tS227.6,9.9,227.4,9.8z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M204.5,13.4c-0.1-0.1,2-1,3.2-1.1c1.2-0.1,2,0,2,0.3c0,0.3-0.1,0.5-1.6,0.4\tC206.4,12.9,204.6,13.5,204.5,13.4z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M201,10.6c0-0.1-4.4,1.2-6.3,2.2c-1.9,0.9-6.2,3.1-6.1,3.1c0.1,0.1,4.2-1.6,6.3-2.6\tS201,10.7,201,10.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M154.5,26.7c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC152.6,27.5,154.6,26.8,154.5,26.7z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M41.9,19.3c0,0,1.2-0.3,2.9-0.1c1.7,0.2,5.8,0.9,8.2,0.7c4.2-0.4,7.4-2.7,7-2.6\tc-0.4,0-4.3,2.2-8.6,1.9c-1.8-0.1-5.1-0.5-6.7-0.4S41.9,19.3,41.9,19.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M75.5,12.6c0.2,0.1,2-0.8,4.3-1.1c2.3-0.2,2.1-0.3,2.1-0.5c0-0.1-1.8-0.4-3.4,0\tC76.9,11.5,75.3,12.5,75.5,12.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M15.6,13.2c0-0.1,4.3,0,6.7,0.5c2.4,0.5,5,1.9,5,2c0,0.1-2.7-0.8-5.1-1.4\tC19.9,13.7,15.7,13.3,15.6,13.2z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b8ae9bc e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"b8ae9bc\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2dc7915 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"2dc7915\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-bf7c31d e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"bf7c31d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a936a0 elementor-widget elementor-widget-image\" data-id=\"7a936a0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"178\" height=\"91\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2021\/10\/waves-small.png\" class=\"attachment-large size-large wp-image-17113\" alt=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e15c6a2 elementor-widget elementor-widget-heading\" data-id=\"e15c6a2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 14px;font-weight: 500;color : black\">Canoa Castelnaud<\/span><br><span style=\"font-weight:700\">\u00a1LOS CLIENTES ALZAN LA VOZ!<\/span> : \u00a1LOS REMEROS <span style=\"font-weight:700\">HABLAN<\/span>!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a31f527 elementor-widget elementor-widget-text-editor\" data-id=\"a31f527\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Lea las opiniones de <strong>nuestros palistas<\/strong> sobre la excursi\u00f3n en canoa entre Vitrac y Castelnaud.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9973fbb e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"9973fbb\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:30}\">\n\t\t<div class=\"elementor-element elementor-element-a0c9c33 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"a0c9c33\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b349b26 elementor-widget elementor-widget-eael-testimonial\" data-id=\"b349b26\" data-element_type=\"widget\" data-widget_type=\"eael-testimonial.default\">\n\t\t\t\t\t\n\t<div id=\"eael-testimonial-b349b26\" class=\"eael-testimonial-item clearfix testimonial-avatar-rounded default-style\">\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-image\">\n\t\t\t\t\t\t\t\t\t<figure><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/unnamed-14.webp\" class=\"attachment-thumbnail size-thumbnail wp-image-4178\" alt=\"Photo de profil avis client Cano\u00ebs Loisirs\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/unnamed-14.webp 120w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/unnamed-14-100x100.webp 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"eael-testimonial-content\">\n\t\t\t\t<div class=\"eael-testimonial-text\"><p>\u00abUn hermoso recorrido de Vitrac a Castelnaud.<br>La bienvenida fue c\u00e1lida y el instructor fue muy amable al recogernos.<br>En cuanto a la ruta, \u00bfqu\u00e9 puedo decir? Un paisaje extraordinario y refrescante.<br>\u00a1Muy recomendable!\u00bb<\/p><\/div><p class=\"eael-testimonial-user\" style=\"display: block; float: none;\">Simon B.<\/p><p class=\"eael-testimonial-user-company\">Agosto de 2023<\/p>\t\t\t<\/div>\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<span class=\"eael-testimonial-quote\"><\/span>\n\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ab7a61 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"4ab7a61\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-943aa6d elementor-widget elementor-widget-eael-testimonial\" data-id=\"943aa6d\" data-element_type=\"widget\" data-widget_type=\"eael-testimonial.default\">\n\t\t\t\t\t\n\t<div id=\"eael-testimonial-943aa6d\" class=\"eael-testimonial-item clearfix testimonial-avatar-rounded default-style\">\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-image\">\n\t\t\t\t\t\t\t\t\t<figure><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/unnamed-15.webp\" class=\"attachment-thumbnail size-thumbnail wp-image-4179\" alt=\"Photo de profil avis client Cano\u00ebs Loisirs\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/unnamed-15.webp 120w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/unnamed-15-100x100.webp 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"eael-testimonial-content\">\n\t\t\t\t<div class=\"eael-testimonial-text\"><p>\u00abUna bienvenida estupenda, vistas preciosas en el descenso a Castelnau.<br>Sin embargo, la ruta de dos horas y media es suficiente; despu\u00e9s, te duelen los brazos.<br>El conductor del autob\u00fas, mayor, es encantador\u00bb<\/p><\/div><p class=\"eael-testimonial-user\" style=\"display: block; float: none;\">Logan Larguier<\/p><p class=\"eael-testimonial-user-company\">Agosto de 2023<\/p>\t\t\t<\/div>\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<span class=\"eael-testimonial-quote\"><\/span>\n\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5be908c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"5be908c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-03fad8a elementor-widget elementor-widget-eael-testimonial\" data-id=\"03fad8a\" data-element_type=\"widget\" data-widget_type=\"eael-testimonial.default\">\n\t\t\t\t\t\n\t<div id=\"eael-testimonial-03fad8a\" class=\"eael-testimonial-item clearfix testimonial-avatar-rounded default-style\">\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-image\">\n\t\t\t\t\t\t\t\t\t<figure><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/unnamed-16.webp\" class=\"attachment-thumbnail size-thumbnail wp-image-4180\" alt=\"Photo de profil avis client Cano\u00ebs Loisirs\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/unnamed-16.webp 120w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/unnamed-16-100x100.webp 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"eael-testimonial-content\">\n\t\t\t\t<div class=\"eael-testimonial-text\"><p>\u00abUn buen viaje de 12 km que hicimos en 1 hora y 45 minutos (2 adultos que ya hab\u00edan hecho algo de pirag\u00fcismo). \u00ab\u00a1Recibimos una c\u00e1lida bienvenida de parte de todos, incluido el personal!<br>Reservamos en l\u00ednea para las 14:00 y pudimos salir a la 13:45. \u00a1El canotaje por el Dordo\u00f1a fue fant\u00e1stico, es precioso!<br>Recomendamos encarecidamente Cano\u00eb Loisirs\u00bb<\/p><\/div><p class=\"eael-testimonial-user\" style=\"display: block; float: none;\">Aur\u00e9lia Garnier<\/p><p class=\"eael-testimonial-user-company\">Agosto de 2023<\/p>\t\t\t<\/div>\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<span class=\"eael-testimonial-quote\"><\/span>\n\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-987bb6b e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"987bb6b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-80a654d e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"80a654d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f8ec9da e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"f8ec9da\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1438606 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"1438606\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-281fc4f elementor-widget elementor-widget-image\" data-id=\"281fc4f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"178\" height=\"91\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2021\/10\/waves-small.png\" class=\"attachment-large size-large wp-image-17113\" alt=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cddd011 elementor-widget elementor-widget-heading\" data-id=\"cddd011\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-weight:300;color:black!important\">Quiere <\/span>descubrir otras rutas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b5ecbd elementor-widget elementor-widget-text-editor\" data-id=\"0b5ecbd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Explore<\/strong> nuevos horizontes Descubra nuestros otros <strong>viajes en canoa<\/strong> para vivir aventuras variadas y disfrutar de paisajes impresionantes a lo largo de la Dordo\u00f1a.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-868f1c3 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"868f1c3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-48e6f4c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"48e6f4c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-89a563a wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"89a563a\" data-element_type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0511-scaled.webp);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-jazz\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/03\/PICTO_OR.svg\" alt=\"\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span><span style=\"font-weight:400\">VITRAC<\/span> <br>BEYNAC <SPAN style=\"font-weight:400\">valle de los 5 castillos<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"https:\/\/canoes-loisirs.com\/es\/curso-de-piraguismo-en-dordona\/vitrac-beynac\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">VER LA RUTA<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\r\n\t\t\t<div class=\"wpr-promo-box-badge wpr-promo-box-badge-corner wpr-promo-box-badge-right\">\r\n\t\t\t\t<div class=\"wpr-promo-box-badge-inner\">3h - 16 KMS<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-907f92c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"907f92c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aafb90a wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"aafb90a\" data-element_type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.0500.webp);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-jazz\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span><span style=\"font-weight:400\">CARSAC<\/span> <br>BEYNAC <br><span style=\"font-weight:400\">el val\u00e9e de los 6 castillos<\/span><\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"https:\/\/canoes-loisirs.com\/es\/curso-de-piraguismo-en-dordona\/carsac-beynac\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">VER LA RUTA<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\r\n\t\t\t<div class=\"wpr-promo-box-badge wpr-promo-box-badge-corner wpr-promo-box-badge-right\">\r\n\t\t\t\t<div class=\"wpr-promo-box-badge-inner\">4h30 - 25 KMS<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70fd090 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"70fd090\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3cea96a wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"3cea96a\" data-element_type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/Com-Images.8559-scaled.webp);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-jazz\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span><span style=\"font-weight:400\">CARSAC<\/span> <br>VITRAC <br><span style=\"font-weight:400\">el circuito de Montfort<\/span><\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"https:\/\/canoes-loisirs.com\/es\/curso-de-piraguismo-en-dordona\/carsac-vitrac\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">VER LA RUTA<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\r\n\t\t\t<div class=\"wpr-promo-box-badge wpr-promo-box-badge-corner wpr-promo-box-badge-right\">\r\n\t\t\t\t<div class=\"wpr-promo-box-badge-inner\">1h30 - 9 KMS<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7cb3ed1 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"7cb3ed1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;waves&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M421.9,6.5c22.6-2.5,51.5,0.4,75.5,5.3c23.6,4.9,70.9,23.5,100.5,35.7c75.8,32.2,133.7,44.5,192.6,49.7\n\tc23.6,2.1,48.7,3.5,103.4-2.5c54.7-6,106.2-25.6,106.2-25.6V0H0v30.3c0,0,72,32.6,158.4,30.5c39.2-0.7,92.8-6.7,134-22.4\n\tc21.2-8.1,52.2-18.2,79.7-24.2C399.3,7.9,411.6,7.5,421.9,6.5z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dffb1bc e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"dffb1bc\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e9b41a2 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"e9b41a2\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6289652 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"6289652\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4bf94c7 elementor-widget elementor-widget-image\" data-id=\"4bf94c7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"178\" height=\"91\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2021\/10\/icon-zigzag.png\" class=\"attachment-large size-large wp-image-17353\" alt=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f698c elementor-widget elementor-widget-heading\" data-id=\"03f698c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VIAJE EN CANOA\n<span style=\"font-weight: 200\">AUTOGUIADO EN VIVAC<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e21148 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"6e21148\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-aa67f15 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"aa67f15\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-94e41aa wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"94e41aa\" data-element_type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2022\/12\/efvefh.webp);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-chicho\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>descubre el <span style=\"font-weight:700\">pirag\u00fcismo<\/span><\/span><\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-description\">\n\t\t\t\t\t\t<p><p>De 2 a 5 d\u00edas para descubrir la naturaleza y la belleza de la Dordo\u00f1a.<\/p><\/p>\t\n\t\t\t\t\t<\/div>\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"https:\/\/canoes-loisirs.com\/es\/piraguismo-en-dordona\/randonnee-liberte\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Descubra<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9c1fc54 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"9c1fc54\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0144201 wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"0144201\" data-element_type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/canoes-bivouac.webp);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-jazz\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span><span style=\"font-weight:700\">RECOMENDACIONES<\/span> Y CONSEJOS<\/span><\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-description\">\n\t\t\t\t\t\t<p><p>Descubra nuestros mejores consejos para disfrutar de una experiencia inolvidable en canoa.<\/p><\/p>\t\n\t\t\t\t\t<\/div>\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"https:\/\/canoes-loisirs.com\/es\/nuestros-consejos-faq\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">M\u00e1s informaci\u00f3n<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b34b67c e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"b34b67c\" data-element_type=\"container\" id=\"widget_add_to_cart\" data-settings=\"{&quot;sticky&quot;:&quot;bottom&quot;,&quot;sticky_offset_mobile&quot;:20,&quot;sticky_effects_offset_mobile&quot;:100,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18da310 elementor-widget elementor-widget-premium-addon-image-button\" data-id=\"18da310\" data-element_type=\"widget\" data-widget_type=\"premium-addon-image-button.default\">\n\t\t\t\t\t\n\t\t<a class=\"premium-image-button-none premium-image-button premium-btn-lg premium-image-button-none\" href=\"https:\/\/canoesloisirs.ats-sarlat.com:8443\/cgi-bin\/ProgATS\/eCommerce?licence=24CANOES_LOIS02&#038;lg=EN&#038;prest=VITCAST\" target=\"_blank\" rel=\"noopener\">\n\t\t\t<div class=\"premium-image-button-text-icon-wrapper\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\tLIBRO <span style=\"font-weight:600\">mi descenso<\/span>\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/a>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Excursi\u00f3n en canoaVITRAC castelnaudVALLE DE LOS DOS CASTILLOS Explore la ruta entre Vitrac y Castelnaud y disfrute de una experiencia inolvidable a lo largo de la Dordo\u00f1a. Reme entre los pintorescos paisajes de la regi\u00f3n y emp\u00e1pese de la historia y la belleza natural que le rodea. \u00a1Le espera una emocionante aventura con Canoe Loisirs! reservar ahora descenso 12 km a pasear ~ 2 h30 Canoa castelnaudDescubre los tesoros del valle de los 2 castillos La ruta en canoa Vitrac &#8211; Castelnaud es una una experiencia inolvidable que le permitir\u00e1 descubrir la belleza del r\u00edo Dordo\u00f1a desde una nueva perspectiva.Esta ruta es imprescindible para los amantes de la naturaleza y los exploradores. Con 12 kil\u00f3metros de longitud, le llevar\u00e1 a trav\u00e9s de los paisajes m\u00e1s bellos del valle del Dordo\u00f1a. Encuentro en la base de Canoe Loisirs en el puerto de Vitrac. Aparque el coche y s\u00fabase a su canoa en 10 minutos. Reservar una hora para nuestra organizaci\u00f3n Salidas continuas de 9.30 a 15.00 horas. Elige una hora de salida para ayudar aorganizar el Equipo Amarillo. Ruta sin estr\u00e9s T\u00f3mese su tiempo para disfrutar al m\u00e1ximo de su descenso. T\u00f3mese un descanso para nadar, visitar un pueblo y hacer fotos. No te preocupes por dejar tu barca junto al r\u00edo. CONSEJOS DEL EQUIPO AMARILLO Antes de salir, un miembro de nuestro equipo se reunir\u00e1 con usted y le explicar\u00e1 todo sobre su ruta y c\u00f3mo dirigir una canoa. TRANSPORTE DE VUELTA Tras el descenso, un autob\u00fas te llevar\u00e1 de vuelta al punto de partida.Los autobuses salen continuamente cada hora (seg\u00fan la temporada; m\u00e1s informaci\u00f3n disponible en el sitio antes de tu salida). por adulto 21 \u20ac pirag\u00fcismo para ni\u00f1os de 5 a 12 a\u00f1os 12.5 \u20ac Kayak para adultos o ni\u00f1os 25 \u20ac Excursi\u00f3n en canoa por CastelnaudPrograma de la excursi\u00f3n Nos vemos en nuestra base de canoas en Vitrac.Se proporcionar\u00e1 equipo (canoas, chalecos salvavidas, remos, bolsas impermeables), y consejos de seguridad. Traslado en autob\u00fas al punto de partida: Salida Base de Cano\u00ebs LoisirsSalida de Vitrac \u00bfEst\u00e1 preparado para una aventura inolvidable? Comience su viaje desde nuestro punto de partida en Vitrac y d\u00e9jese hechizar por la belleza natural de la Dordo\u00f1a. Tanto si es un principiante como un experto pirag\u00fcista, nuestro equipo est\u00e1 aqu\u00ed para ayudarle a disfrutar de momentos de puro placer y descubrimiento. Prep\u00e1rese para crear recuerdos inolvidables con Canoe Loisirs. 3 km La Bastida de Domme Descubra la belleza intemporal de Domme desde la comodidad de su canoa. Encaramado en un acantilado con vistas a la Dordo\u00f1a, este pueblo medieval ofrece panoramas impresionantes que son realmente \u00fanicos. Reme a lo largo de sus murallas y d\u00e9jese seducir por su encanto hist\u00f3rico. 7,3 km La Roque-Gajeac \u00a1Explore la historia desde su canoa en La Roque-Gageac! Este pueblo troglodita encaramado a orillas del Dordo\u00f1a ofrece unas vistas impresionantes desde el agua. Desl\u00edcese entre sus pintorescas casas y contemple los acantilados que la dominan. 7,8 km Castillo de la Malartrie \u00a1Contemple el Castillo de la Malartrie desde su canoa! Enclavado a orillas del Dordo\u00f1a, este castillo ofrece una vista majestuosa desde el agua. Reme tranquilamente mientras admira su elegante arquitectura y su encantador entorno natural. Llegada Castelnaud-la-Chapelle Su llegada a Castelnaud es un momento emocionante. Una vez desembarcado, ser\u00e1 recibido por las majestuosas torres del castillo medieval, que se yerguen orgullosas sobre la Dordo\u00f1a. Nuestra lanzadera le recoger\u00e1 y le llevar\u00e1 de vuelta a la base de Vitrac. AVENTURERO PERO NO REDENTORESPECIALMENTE BAJO LA LLUVIA Opta por tu billete con fecha modificable Disfruta de un paseo bajo el hermoso sol de Dordo\u00f1a.La \u00fanica regla: av\u00edsanos con 36 horas de antelaci\u00f3n Ahorre tiempo a su llegada Un miembro del Equipo Amarillo se har\u00e1 cargo de usted lo antes posible para minimizar el tiempo de espera. Un paseo al sol Cambie su fecha con hasta 36 horas de antelaci\u00f3n para asegurarse un viaje soleado. Garantizarse una canoa El Equipo Amarillo garantiza la disponibilidad de canoas para todos los titulares de un billete intercambiable. Canoa Castelnaud\u00a1LOS CLIENTES ALZAN LA VOZ! : \u00a1LOS REMEROS HABLAN! Lea las opiniones de nuestros palistas sobre la excursi\u00f3n en canoa entre Vitrac y Castelnaud. \u00ab\u00a0Un hermoso recorrido de Vitrac a Castelnaud.La bienvenida fue c\u00e1lida y el instructor fue muy amable al recogernos.En cuanto a la ruta, \u00bfqu\u00e9 puedo decir? Un paisaje extraordinario y refrescante.\u00a1Muy recomendable!\u00a0\u00bb Simon B. Agosto de 2023 \u00ab\u00a0Una bienvenida estupenda, vistas preciosas en el descenso a Castelnau.Sin embargo, la ruta de dos horas y media es suficiente; despu\u00e9s, te duelen los brazos.El conductor del autob\u00fas, mayor, es encantador\u00a0\u00bb Logan Larguier Agosto de 2023 \u00ab\u00a0Un buen viaje de 12 km que hicimos en 1 hora y 45 minutos (2 adultos que ya hab\u00edan hecho algo de pirag\u00fcismo). \u00ab\u00a0\u00a1Recibimos una c\u00e1lida bienvenida de parte de todos, incluido el personal!Reservamos en l\u00ednea para las 14:00 y pudimos salir a la 13:45. \u00a1El canotaje por el Dordo\u00f1a fue fant\u00e1stico, es precioso!Recomendamos encarecidamente Cano\u00eb Loisirs\u00a0\u00bb Aur\u00e9lia Garnier Agosto de 2023 Quiere descubrir otras rutas Explore nuevos horizontes Descubra nuestros otros viajes en canoa para vivir aventuras variadas y disfrutar de paisajes impresionantes a lo largo de la Dordo\u00f1a. VITRAC BEYNAC valle de los 5 castillos VER LA RUTA 3h &#8211; 16 KMS CARSAC BEYNAC el val\u00e9e de los 6 castillos VER LA RUTA 4h30 &#8211; 25 KMS CARSAC VITRAC el circuito de Montfort VER LA RUTA 1h30 &#8211; 9 KMS VIAJE EN CANOA AUTOGUIADO EN VIVAC descubre el pirag\u00fcismo De 2 a 5 d\u00edas para descubrir la naturaleza y la belleza de la Dordo\u00f1a. Descubra RECOMENDACIONES Y CONSEJOS Descubra nuestros mejores consejos para disfrutar de una experiencia inolvidable en canoa. M\u00e1s informaci\u00f3n LIBRO mi descenso<\/p>\n","protected":false},"author":8105,"featured_media":0,"parent":19276,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-full-width-page-without-header-title.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-19296","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/canoes-loisirs.com\/es\/wp-json\/wp\/v2\/pages\/19296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canoes-loisirs.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/canoes-loisirs.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/canoes-loisirs.com\/es\/wp-json\/wp\/v2\/users\/8105"}],"replies":[{"embeddable":true,"href":"https:\/\/canoes-loisirs.com\/es\/wp-json\/wp\/v2\/comments?post=19296"}],"version-history":[{"count":24,"href":"https:\/\/canoes-loisirs.com\/es\/wp-json\/wp\/v2\/pages\/19296\/revisions"}],"predecessor-version":[{"id":26401,"href":"https:\/\/canoes-loisirs.com\/es\/wp-json\/wp\/v2\/pages\/19296\/revisions\/26401"}],"up":[{"embeddable":true,"href":"https:\/\/canoes-loisirs.com\/es\/wp-json\/wp\/v2\/pages\/19276"}],"wp:attachment":[{"href":"https:\/\/canoes-loisirs.com\/es\/wp-json\/wp\/v2\/media?parent=19296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}