{"id":22349,"date":"2024-05-30T13:38:28","date_gmt":"2024-05-30T11:38:28","guid":{"rendered":"https:\/\/canoes-loisirs.com\/tarife\/"},"modified":"2024-07-19T00:08:41","modified_gmt":"2024-07-18T22:08:41","slug":"tarife","status":"publish","type":"page","link":"https:\/\/canoes-loisirs.com\/de\/tarife\/","title":{"rendered":"Tarife"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"22349\" class=\"elementor elementor-22349 elementor-22056\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b7326b0 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"b7326b0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;wave-brush&quot;}\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 283.5 27.8\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M283.5,9.7c0,0-7.3,4.3-14,4.6c-6.8,0.3-12.6,0-20.9-1.5c-11.3-2-33.1-10.1-44.7-5.7\ts-12.1,4.6-18,7.4c-6.6,3.2-20,9.6-36.6,9.3C131.6,23.5,99.5,7.2,86.3,8c-1.4,0.1-6.6,0.8-10.5,2c-3.8,1.2-9.4,3.8-17,4.7\tc-3.2,0.4-8.3,1.1-14.2,0.9c-1.5-0.1-6.3-0.4-12-1.6c-5.7-1.2-11-3.1-15.8-3.7C6.5,9.2,0,10.8,0,10.8V0h283.5V9.7z M260.8,11.3\tc-0.7-1-2-0.4-4.3-0.4c-2.3,0-6.1-1.2-5.8-1.1c0.3,0.1,3.1,1.5,6,1.9C259.7,12.2,261.4,12.3,260.8,11.3z M242.4,8.6\tc0,0-2.4-0.2-5.6-0.9c-3.2-0.8-10.3-2.8-15.1-3.5c-8.2-1.1-15.8,0-15.1,0.1c0.8,0.1,9.6-0.6,17.6,1.1c3.3,0.7,9.3,2.2,12.4,2.7\tC239.9,8.7,242.4,8.6,242.4,8.6z M185.2,8.5c1.7-0.7-13.3,4.7-18.5,6.1c-2.1,0.6-6.2,1.6-10,2c-3.9,0.4-8.9,0.4-8.8,0.5\tc0,0.2,5.8,0.8,11.2,0c5.4-0.8,5.2-1.1,7.6-1.6C170.5,14.7,183.5,9.2,185.2,8.5z M199.1,6.9c0.2,0-0.8-0.4-4.8,1.1\tc-4,1.5-6.7,3.5-6.9,3.7c-0.2,0.1,3.5-1.8,6.6-3C197,7.5,199,6.9,199.1,6.9z M283,6c-0.1,0.1-1.9,1.1-4.8,2.5s-6.9,2.8-6.7,2.7\tc0.2,0,3.5-0.6,7.4-2.5C282.8,6.8,283.1,5.9,283,6z M31.3,11.6c0.1-0.2-1.9-0.2-4.5-1.2s-5.4-1.6-7.8-2C15,7.6,7.3,8.5,7.7,8.6\tC8,8.7,15.9,8.3,20.2,9.3c2.2,0.5,2.4,0.5,5.7,1.6S31.2,11.9,31.3,11.6z M73,9.2c0.4-0.1,3.5-1.6,8.4-2.6c4.9-1.1,8.9-0.5,8.9-0.8\tc0-0.3-1-0.9-6.2-0.3S72.6,9.3,73,9.2z M71.6,6.7C71.8,6.8,75,5.4,77.3,5c2.3-0.3,1.9-0.5,1.9-0.6c0-0.1-1.1-0.2-2.7,0.2\tC74.8,5.1,71.4,6.6,71.6,6.7z M93.6,4.4c0.1,0.2,3.5,0.8,5.6,1.8c2.1,1,1.8,0.6,1.9,0.5c0.1-0.1-0.8-0.8-2.4-1.3\tC97.1,4.8,93.5,4.2,93.6,4.4z M65.4,11.1c-0.1,0.3,0.3,0.5,1.9-0.2s2.6-1.3,2.2-1.2s-0.9,0.4-2.5,0.8C65.3,10.9,65.5,10.8,65.4,11.1\tz M34.5,12.4c-0.2,0,2.1,0.8,3.3,0.9c1.2,0.1,2,0.1,2-0.2c0-0.3-0.1-0.5-1.6-0.4C36.6,12.8,34.7,12.4,34.5,12.4z M152.2,21.1\tc-0.1,0.1-2.4-0.3-7.5-0.3c-5,0-13.6-2.4-17.2-3.5c-3.6-1.1,10,3.9,16.5,4.1C150.5,21.6,152.3,21,152.2,21.1z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M269.6,18c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC267.7,18.8,269.7,18,269.6,18z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M227.4,9.8c-0.2-0.1-4.5-1-9.5-1.2c-5-0.2-12.7,0.6-12.3,0.5c0.3-0.1,5.9-1.8,13.3-1.2\tS227.6,9.9,227.4,9.8z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M204.5,13.4c-0.1-0.1,2-1,3.2-1.1c1.2-0.1,2,0,2,0.3c0,0.3-0.1,0.5-1.6,0.4\tC206.4,12.9,204.6,13.5,204.5,13.4z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M201,10.6c0-0.1-4.4,1.2-6.3,2.2c-1.9,0.9-6.2,3.1-6.1,3.1c0.1,0.1,4.2-1.6,6.3-2.6\tS201,10.7,201,10.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M154.5,26.7c-0.1-0.1-4.6,0.3-7.2,0c-7.3-0.7-17-3.2-16.6-2.9c0.4,0.3,13.7,3.1,17,3.3\tC152.6,27.5,154.6,26.8,154.5,26.7z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M41.9,19.3c0,0,1.2-0.3,2.9-0.1c1.7,0.2,5.8,0.9,8.2,0.7c4.2-0.4,7.4-2.7,7-2.6\tc-0.4,0-4.3,2.2-8.6,1.9c-1.8-0.1-5.1-0.5-6.7-0.4S41.9,19.3,41.9,19.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M75.5,12.6c0.2,0.1,2-0.8,4.3-1.1c2.3-0.2,2.1-0.3,2.1-0.5c0-0.1-1.8-0.4-3.4,0\tC76.9,11.5,75.3,12.5,75.5,12.6z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M15.6,13.2c0-0.1,4.3,0,6.7,0.5c2.4,0.5,5,1.9,5,2c0,0.1-2.7-0.8-5.1-1.4\tC19.9,13.7,15.7,13.3,15.6,13.2z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30ab3ee e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"30ab3ee\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1da7313 elementor-widget elementor-widget-html\" data-id=\"1da7313\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<script src=\"https:\/\/kit.fontawesome.com\/7f56f1ad92.js\" crossorigin=\"anonymous\"><\/script>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29888a0 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"29888a0\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3d504c1 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"3d504c1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2b7a5a elementor-widget elementor-widget-image\" data-id=\"c2b7a5a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"178\" height=\"91\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2021\/10\/waves-small.png\" class=\"attachment-medium size-medium wp-image-17112\" alt=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4063797 elementor-widget elementor-widget-text-editor\" data-id=\"4063797\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 200; color: #fcd701;\">WE ARE<\/span> YELLOW<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9aee5e3 elementor-widget elementor-widget-heading\" data-id=\"9aee5e3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-weight:800\">Entdecken Sie die Preise <\/span><br> von Cano\u00ebs Loisirs<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fbd26a elementor-widget elementor-widget-text-editor\" data-id=\"8fbd26a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Sind Sie bereit f\u00fcr ein unvergessliches Abenteuer auf der Dordogne ? Entdecken Sie unsere Streckenoptionen und unsere attraktiven Preise f\u00fcr ein einzigartiges Kanu-Erlebnis. Egal, ob Sie Anf\u00e4nger oder Fortgeschrittener sind, allein, mit der Familie oder mit Freunden, wir haben die passende Strecke f\u00fcr Sie.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1cc7dc elementor-widget elementor-widget-html\" data-id=\"f1cc7dc\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t  <script>const header = document.getElementById(\"pr-nav\");\n\n    const links = document.querySelectorAll('.nav-link');\n    \n    const phones = document.querySelectorAll('.header-phone');\n    \n    const search = document.querySelectorAll('.search-icon');\n    \n    const menus = document.querySelectorAll('.menu-item');\n    \n    const cta = document.querySelectorAll('.header-cta');\n    \n    const logo = document.getElementsByClassName('custom-logo').item(0);\n    \n    let img = logo.getAttribute(\"src\");\n    if(screen.width <801) { logo.src =\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/01\/cropped-CANOELOISIRS-2048x535.png\"; }else{ logo.src =\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/cropped-logo-blan-cl.png\" } function changeLogo (logo) { logo.src = 'https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/01\/cropped-CANOELOISIRS-2048x535.png' }; function removeLogo (logo) { logo.src = 'https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/02\/cropped-logo-blan-cl.png' }; if(screen.width> 801) {    \nwindow.addEventListener('scroll', () =>{\n    if(window.scrollY > 0){\n        header.classList.add('scrolled');\n        links.forEach((link) => {\n            link.classList.add('nav-link-scrolled');\n            });\n        phones.forEach((phone) => {\n            phone.classList.add('nav-link-scrolled');\n            });\n        search.forEach((icon) => {\n            icon.classList.add('nav-link-scrolled');\n        });\n        menus.forEach((menu) => {\n            menu.classList.add('nav-link-scrolled');\n        });\n        cta.forEach((button) => {\n            button.classList.add('cta-scrolled');\n        });\n        changeLogo(logo);\n        \n        \n    }else{\n        header.classList.remove('scrolled');\n        links.forEach((link) => {\n            link.classList.remove('nav-link-scrolled');\n        });\n        phones.forEach((phone) => {\n            phone.classList.remove('nav-link-scrolled');\n        });\n        search.forEach((icon) => {\n            icon.classList.remove('nav-link-scrolled');\n        });\n        menus.forEach((menu) => {\n            menu.classList.remove('nav-link-scrolled');\n        });\n        cta.forEach((button) => {\n            button.classList.remove('cta-scrolled');\n        });\n        removeLogo(logo);\n    }\n})\n}\n <\/script>   \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-07a3416 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"07a3416\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d51c026 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"d51c026\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1efc1f0 eael-dt-th-align-center eael-table-align-center elementor-widget elementor-widget-eael-data-table\" data-id=\"1efc1f0\" data-element_type=\"widget\" data-widget_type=\"eael-data-table.default\">\n\t\t\t\t\t<style>\n\t\t\t@media (max-width: 767px) {\n\t\t\t   #eael-data-table-wrapper-1efc1f0.custom-responsive-option-enable .eael-data-table thead {\n                    display: none;\n               }\n               #eael-data-table-wrapper-1efc1f0.custom-responsive-option-enable .eael-data-table tbody tr td {\n                    float: none;\n                    clear: left;\n                    width: 100%;\n                    text-align: left;\n                    display: flex;\n                    align-items: center;\n                }\n\t\t\t}\n\t\t\t<\/style>\t\t<div class=\"eael-data-table-wrap custom-responsive-option-enable\" data-table_id=\"1efc1f0\" id=\"eael-data-table-wrapper-1efc1f0\" data-custom_responsive=\"true\">\n\t\t\t<table class=\"tablesorter eael-data-table center\" id=\"eael-data-table-1efc1f0\">\n\t\t\t    <thead>\n\t\t\t        <tr class=\"table-header\">\n\t\t\t\t\t\t\t\t\t            <th class=\"\" id=\"\" colspan=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"data-table-header-text\">Parcours<\/span><\/th>\n\t\t\t        \t\t\t\t            <th class=\"\" id=\"\" colspan=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"data-table-header-text\">Erwachsener im Kanu<\/span><\/th>\n\t\t\t        \t\t\t\t            <th class=\"\" id=\"\" colspan=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"data-table-header-text\">Kind von 5 bis 12 Jahren im Kanu der Eltern<\/span><\/th>\n\t\t\t        \t\t\t\t            <th class=\"\" id=\"\" colspan=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"data-table-header-text\">Einsitzer-Kajak \/ Doppelkajak<\/span><\/th>\n\t\t\t        \t\t\t\t        <\/tr>\n\t\t\t    <\/thead>\n\t\t\t  \t<tbody>\n\t\t\t\t\t\t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/canoes-loisirs.com\/de\/kanustrecke-dordogne\/carsac-vitrac\/\">Carsac &gt; Vitrac <br> Der Wittling von Montfort<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t17\u20ac\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t10.5\u20ac\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t20\u20ac\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/canoes-loisirs.com\/de\/kanustrecke-dordogne\/calviac-vitrac\/\">Calviac &gt; Vitrac <br> Natur-Parcours<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t23\u20ac\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t14\u20ac\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t26\u20ac\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/canoes-loisirs.com\/de\/kanustrecke-dordogne\/vitrac-castelnaud\/\">Vitrac &gt; Castelnaud <br> Tal der 2 Schl\u00f6sser<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t20\u20ac\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t12\u20ac\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t23\u20ac\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/canoes-loisirs.com\/de\/kanustrecke-dordogne\/vitrac-beynac\/\">Vitrac &gt; Beynac <br> Tal der 5 Schl\u00f6sser<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t22\u20ac\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t13\u20ac\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t25\u20ac\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/canoes-loisirs.com\/de\/kanustrecke-dordogne\/carsac-beynac\/\">Carsac &gt; Beynac <br> Tal der 6 Schl\u00f6sser<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t26\u20ac\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t15\u20ac\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t29\u20ac\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t    <\/tbody>\n\t\t\t<\/table>\n\t\t<\/div>\n\t  \t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cb10cc7 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"cb10cc7\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1fed60b e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"1fed60b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ec2839 eael-infobox-content-align--center eael-infobox-shape-square eael-infobox-hover-img-shape-square elementor-widget elementor-widget-eael-info-box\" data-id=\"1ec2839\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon\">\n\n                            <img decoding=\"async\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/03\/fav_cane.webp\" alt=\"Favicon Cano\u00ebs Loisirs\">\n            \n            \n            \n        <\/div>\n            <div class=\"infobox-content\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">Angepasstes Material<\/h3>            <\/div>\n            <div><p>Unsere Kanu-Basis ist mit allem ausgestattet, was Sie brauchen, um ein 100%iges Naturabenteuer entlang der Dordogne zu genie\u00dfen.<\/p>\n<\/p>\n<p><strong>Unsere Kanus und Kajaks mit bequemen R\u00fcckenlehnen sorgen daf\u00fcr, dass Sie ein angenehmes Erlebnis haben werden !<\/strong><\/p>\n<\/div>        <div class=\"infobox-button\">\n            <a class=\"eael-infobox-button\">\n                                                <span class=\"infobox-button-text\"><\/span>\n                            <\/a>\n        <\/div>\n            <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-368c726 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"368c726\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0b68b1 eael-infobox-content-align--center eael-infobox-shape-square eael-infobox-hover-img-shape-square elementor-widget elementor-widget-eael-info-box\" data-id=\"a0b68b1\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon\">\n\n                            <img decoding=\"async\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/03\/fav_cane.webp\" alt=\"Favicon Cano\u00ebs Loisirs\">\n            \n            \n            \n        <\/div>\n            <div class=\"infobox-content\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">Ein kostenloser Topo-Guide !<\/h3>            <\/div>\n            <div><p>Ein <strong>Flussf\u00fchrer, der in f\u00fcnf Sprachen verf\u00fcgbar is<\/strong>t, wird Ihnen kostenlos zur Verf\u00fcgung gestellt.<\/p>\n<p>Dieser Reisef\u00fchrer hilft Ihnen, den historischen Reichtum des Flusses Esperance zu entdecken, die Qualit\u00e4t dieser gesch\u00fctzten Umgebung zu sch\u00e4tzen und praktische Informationen zu finden.<\/p>\n<\/div>        <div class=\"infobox-button\">\n            <a class=\"eael-infobox-button\">\n                                                <span class=\"infobox-button-text\"><\/span>\n                            <\/a>\n        <\/div>\n            <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f51b8ec e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"f51b8ec\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d4f03b eael-infobox-content-align--center eael-infobox-shape-square eael-infobox-hover-img-shape-square elementor-widget elementor-widget-eael-info-box\" data-id=\"8d4f03b\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon\">\n\n                            <img decoding=\"async\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2024\/03\/fav_cane.webp\" alt=\"Favicon Cano\u00ebs Loisirs\">\n            \n            \n            \n        <\/div>\n            <div class=\"infobox-content\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">Au\u00dfergew\u00f6hnlicher Kundenservice<\/h3>            <\/div>\n            <div><p>Unsere Basis liegt im Herzen des majest\u00e4tischen Dordogne-Tals und <strong>bietet ab 9 Uhr einen Shuttle-Bus an<\/strong>, der Sie zu den von Ihnen gew\u00e4hlten Startpunkten bringt.<\/p>\n<p>Anschlie\u00dfend fahren Sie in Ihrem eigenen Tempo die Dordogne hinunter und kehren zu unserer Basis zur\u00fcck, wo Ihr Auto auf Sie wartet.<\/p>\n<p>Auf dem Programm stehen Entspannung, Baden, Picknicks in v\u00f6lliger Freiheit&#8230; Genie\u00dfen Sie es in vollen Z\u00fcgen!<\/p>\n<\/div>        <div class=\"infobox-button\">\n            <a class=\"eael-infobox-button\">\n                                                <span class=\"infobox-button-text\"><\/span>\n                            <\/a>\n        <\/div>\n            <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-85a3661 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"85a3661\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6705f5e e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"6705f5e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c41f59 elementor-widget elementor-widget-image\" data-id=\"2c41f59\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"256\" height=\"256\" src=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2022\/12\/payjmpng.png\" class=\"attachment-large size-large wp-image-17688\" alt=\"\" srcset=\"https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2022\/12\/payjmpng.png 256w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2022\/12\/payjmpng-150x150.png 150w, https:\/\/canoes-loisirs.com\/wp-content\/uploads\/2022\/12\/payjmpng-100x100.png 100w\" sizes=\"(max-width: 256px) 100vw, 256px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb4537e elementor-widget elementor-widget-heading\" data-id=\"bb4537e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 14px\">Cano\u00ebs Loisirs <\/span><br><span style=\"color:#fcd701;font-weight:400\">DIE REGELN <\/span><br> <span style=\"font-weight:200\">ZURESPEKTIEREN<\/span> ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4ecde6 elementor-widget elementor-widget-text-editor\" data-id=\"a4ecde6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Damit Ihr Kanuabenteuer sicher und f\u00fcr alle Beteiligten angenehm ist, sollten Sie unbedingt einige einfache Regeln beachten. Diese Anweisungen garantieren nicht nur Ihre Sicherheit, sondern auch die Erhaltung der au\u00dfergew\u00f6hnlichen nat\u00fcrlichen Umgebung der Dordogne. Bitte nehmen Sie sich einen Moment Zeit, um sie sorgf\u00e4ltig zu lesen, bevor Sie mit dem Abstieg beginnen. Lassen Sie uns gemeinsam daf\u00fcr sorgen, dass diese Erfahrung f\u00fcr alle Teilnehmer und f\u00fcr zuk\u00fcnftige Generationen unvergesslich bleibt.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-83e5e2d e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"83e5e2d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a69d23c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"a69d23c\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-628dc48 eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"628dc48\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-swimmer\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M189.61 310.58c3.54 3.26 15.27 9.42 34.39 9.42s30.86-6.16 34.39-9.42c16.02-14.77 34.5-22.58 53.46-22.58h16.3c18.96 0 37.45 7.81 53.46 22.58 3.54 3.26 15.27 9.42 34.39 9.42s30.86-6.16 34.39-9.42c14.86-13.71 31.88-21.12 49.39-22.16l-112.84-80.6 18-12.86c3.64-2.58 8.28-3.52 12.62-2.61l100.35 21.53c25.91 5.53 51.44-10.97 57-36.88 5.55-25.92-10.95-51.44-36.88-57L437.68 98.47c-30.73-6.58-63.02.12-88.56 18.38l-80.02 57.17c-10.38 7.39-19.36 16.44-26.72 26.94L173.75 299c5.47 3.23 10.82 6.93 15.86 11.58zM624 352h-16c-26.04 0-45.8-8.42-56.09-17.9-8.9-8.21-19.66-14.1-31.77-14.1h-16.3c-12.11 0-22.87 5.89-31.77 14.1C461.8 343.58 442.04 352 416 352s-45.8-8.42-56.09-17.9c-8.9-8.21-19.66-14.1-31.77-14.1h-16.3c-12.11 0-22.87 5.89-31.77 14.1C269.8 343.58 250.04 352 224 352s-45.8-8.42-56.09-17.9c-8.9-8.21-19.66-14.1-31.77-14.1h-16.3c-12.11 0-22.87 5.89-31.77 14.1C77.8 343.58 58.04 352 32 352H16c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h16c38.62 0 72.72-12.19 96-31.84 23.28 19.66 57.38 31.84 96 31.84s72.72-12.19 96-31.84c23.28 19.66 57.38 31.84 96 31.84s72.72-12.19 96-31.84c23.28 19.66 57.38 31.84 96 31.84h16c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16zm-512-96c44.18 0 80-35.82 80-80s-35.82-80-80-80-80 35.82-80 80 35.82 80 80 80z\"><\/path><\/svg>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">SCHWIMMEN K\u00d6NNEN 25 UND UNTERTAUCHEN<\/h3>            <\/div>\n                    <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed732e5 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"ed732e5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c51b329 eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"c51b329\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-swimming-pool\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M624 416h-16c-26.04 0-45.8-8.42-56.09-17.9-8.9-8.21-19.66-14.1-31.77-14.1h-16.3c-12.11 0-22.87 5.89-31.77 14.1C461.8 407.58 442.04 416 416 416s-45.8-8.42-56.09-17.9c-8.9-8.21-19.66-14.1-31.77-14.1h-16.3c-12.11 0-22.87 5.89-31.77 14.1C269.8 407.58 250.04 416 224 416s-45.8-8.42-56.09-17.9c-8.9-8.21-19.66-14.1-31.77-14.1h-16.3c-12.11 0-22.87 5.89-31.77 14.1C77.8 407.58 58.04 416 32 416H16c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h16c38.62 0 72.72-12.19 96-31.84 23.28 19.66 57.38 31.84 96 31.84s72.72-12.19 96-31.84c23.28 19.66 57.38 31.84 96 31.84s72.72-12.19 96-31.84c23.28 19.66 57.38 31.84 96 31.84h16c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16zm-400-32v-96h192v96c19.12 0 30.86-6.16 34.39-9.42 9.17-8.46 19.2-14.34 29.61-18.07V128c0-17.64 14.36-32 32-32s32 14.36 32 32v16c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-16c0-52.94-43.06-96-96-96s-96 43.06-96 96v96H224v-96c0-17.64 14.36-32 32-32s32 14.36 32 32v16c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-16c0-52.94-43.06-96-96-96s-96 43.06-96 96v228.5c10.41 3.73 20.44 9.62 29.61 18.07 3.53 3.27 15.27 9.43 34.39 9.43z\"><\/path><\/svg>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">Tragen einer Schwimmweste<\/h3>            <\/div>\n                    <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6cb76a8 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"6cb76a8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a1dfe81 eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"a1dfe81\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-ship\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M496.616 372.639l70.012-70.012c16.899-16.9 9.942-45.771-12.836-53.092L512 236.102V96c0-17.673-14.327-32-32-32h-64V24c0-13.255-10.745-24-24-24H248c-13.255 0-24 10.745-24 24v40h-64c-17.673 0-32 14.327-32 32v140.102l-41.792 13.433c-22.753 7.313-29.754 36.173-12.836 53.092l70.012 70.012C125.828 416.287 85.587 448 24 448c-13.255 0-24 10.745-24 24v16c0 13.255 10.745 24 24 24 61.023 0 107.499-20.61 143.258-59.396C181.677 487.432 216.021 512 256 512h128c39.979 0 74.323-24.568 88.742-59.396C508.495 491.384 554.968 512 616 512c13.255 0 24-10.745 24-24v-16c0-13.255-10.745-24-24-24-60.817 0-101.542-31.001-119.384-75.361zM192 128h256v87.531l-118.208-37.995a31.995 31.995 0 0 0-19.584 0L192 215.531V128z\"><\/path><\/svg>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">In der Mitte des Flusses segeln<\/h3>            <\/div>\n                    <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a0729ed e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"a0729ed\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77ccb6e eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"77ccb6e\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tree\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M378.31 378.49L298.42 288h30.63c9.01 0 16.98-5 20.78-13.06 3.8-8.04 2.55-17.26-3.28-24.05L268.42 160h28.89c9.1 0 17.3-5.35 20.86-13.61 3.52-8.13 1.86-17.59-4.24-24.08L203.66 4.83c-6.03-6.45-17.28-6.45-23.32 0L70.06 122.31c-6.1 6.49-7.75 15.95-4.24 24.08C69.38 154.65 77.59 160 86.69 160h28.89l-78.14 90.91c-5.81 6.78-7.06 15.99-3.27 24.04C37.97 283 45.93 288 54.95 288h30.63L5.69 378.49c-6 6.79-7.36 16.09-3.56 24.26 3.75 8.05 12 13.25 21.01 13.25H160v24.45l-30.29 48.4c-5.32 10.64 2.42 23.16 14.31 23.16h95.96c11.89 0 19.63-12.52 14.31-23.16L224 440.45V416h136.86c9.01 0 17.26-5.2 21.01-13.25 3.8-8.17 2.44-17.47-3.56-24.26z\"><\/path><\/svg>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">AN \u00c4STEN UND BAUMST\u00c4MMEN VORBEIFAHREN<\/h3>            <\/div>\n                    <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c43b522 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"c43b522\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b7f9460 eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"b7f9460\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <i aria-hidden=\"true\" class=\"icon icon-map-marker1\"><\/i>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">BADEGEBIETE UMGEHEN<\/h3>            <\/div>\n                    <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59e908c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"59e908c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8eba23c eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"8eba23c\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-water\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M562.1 383.9c-21.5-2.4-42.1-10.5-57.9-22.9-14.1-11.1-34.2-11.3-48.2 0-37.9 30.4-107.2 30.4-145.7-1.5-13.5-11.2-33-9.1-46.7 1.8-38 30.1-106.9 30-145.2-1.7-13.5-11.2-33.3-8.9-47.1 2-15.5 12.2-36 20.1-57.7 22.4-7.9.8-13.6 7.8-13.6 15.7v32.2c0 9.1 7.6 16.8 16.7 16 28.8-2.5 56.1-11.4 79.4-25.9 56.5 34.6 137 34.1 192 0 56.5 34.6 137 34.1 192 0 23.3 14.2 50.9 23.3 79.1 25.8 9.1.8 16.7-6.9 16.7-16v-31.6c.1-8-5.7-15.4-13.8-16.3zm0-144c-21.5-2.4-42.1-10.5-57.9-22.9-14.1-11.1-34.2-11.3-48.2 0-37.9 30.4-107.2 30.4-145.7-1.5-13.5-11.2-33-9.1-46.7 1.8-38 30.1-106.9 30-145.2-1.7-13.5-11.2-33.3-8.9-47.1 2-15.5 12.2-36 20.1-57.7 22.4-7.9.8-13.6 7.8-13.6 15.7v32.2c0 9.1 7.6 16.8 16.7 16 28.8-2.5 56.1-11.4 79.4-25.9 56.5 34.6 137 34.1 192 0 56.5 34.6 137 34.1 192 0 23.3 14.2 50.9 23.3 79.1 25.8 9.1.8 16.7-6.9 16.7-16v-31.6c.1-8-5.7-15.4-13.8-16.3zm0-144C540.6 93.4 520 85.4 504.2 73 490.1 61.9 470 61.7 456 73c-37.9 30.4-107.2 30.4-145.7-1.5-13.5-11.2-33-9.1-46.7 1.8-38 30.1-106.9 30-145.2-1.7-13.5-11.2-33.3-8.9-47.1 2-15.5 12.2-36 20.1-57.7 22.4-7.9.8-13.6 7.8-13.6 15.7v32.2c0 9.1 7.6 16.8 16.7 16 28.8-2.5 56.1-11.4 79.4-25.9 56.5 34.6 137 34.1 192 0 56.5 34.6 137 34.1 192 0 23.3 14.2 50.9 23.3 79.1 25.8 9.1.8 16.7-6.9 16.7-16v-31.6c.1-8-5.7-15.4-13.8-16.3z\"><\/path><\/svg>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">DIE NATUR RESPEKTIEREN<\/h3>            <\/div>\n                    <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d3010ff e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"d3010ff\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc0737b eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"fc0737b\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-fish\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M327.1 96c-89.97 0-168.54 54.77-212.27 101.63L27.5 131.58c-12.13-9.18-30.24.6-27.14 14.66L24.54 256 .35 365.77c-3.1 14.06 15.01 23.83 27.14 14.66l87.33-66.05C158.55 361.23 237.13 416 327.1 416 464.56 416 576 288 576 256S464.56 96 327.1 96zm87.43 184c-13.25 0-24-10.75-24-24 0-13.26 10.75-24 24-24 13.26 0 24 10.74 24 24 0 13.25-10.75 24-24 24z\"><\/path><\/svg>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">DIE FISCHER RESPEKTIEREN<\/h3>            <\/div>\n                    <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e9dce6a e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"e9dce6a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b521183 eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"b521183\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hands-helping\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M488 192H336v56c0 39.7-32.3 72-72 72s-72-32.3-72-72V126.4l-64.9 39C107.8 176.9 96 197.8 96 220.2v47.3l-80 46.2C.7 322.5-4.6 342.1 4.3 357.4l80 138.6c8.8 15.3 28.4 20.5 43.7 11.7L231.4 448H368c35.3 0 64-28.7 64-64h16c17.7 0 32-14.3 32-32v-64h8c13.3 0 24-10.7 24-24v-48c0-13.3-10.7-24-24-24zm147.7-37.4L555.7 16C546.9.7 527.3-4.5 512 4.3L408.6 64H306.4c-12 0-23.7 3.4-33.9 9.7L239 94.6c-9.4 5.8-15 16.1-15 27.1V248c0 22.1 17.9 40 40 40s40-17.9 40-40v-88h184c30.9 0 56 25.1 56 56v28.5l80-46.2c15.3-8.9 20.5-28.4 11.7-43.7z\"><\/path><\/svg>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">H\u00d6FLICH ZU ANWOHNERN UND ANDEREN FLUSSBENUTZERN SEIN<\/h3>            <\/div>\n                    <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d69fcf2 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"d69fcf2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21528d3 eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"21528d3\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-shoe-prints\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M192 160h32V32h-32c-35.35 0-64 28.65-64 64s28.65 64 64 64zM0 416c0 35.35 28.65 64 64 64h32V352H64c-35.35 0-64 28.65-64 64zm337.46-128c-34.91 0-76.16 13.12-104.73 32-24.79 16.38-44.52 32-104.73 32v128l57.53 15.97c26.21 7.28 53.01 13.12 80.31 15.05 32.69 2.31 65.6.67 97.58-6.2C472.9 481.3 512 429.22 512 384c0-64-84.18-96-174.54-96zM491.42 7.19C459.44.32 426.53-1.33 393.84.99c-27.3 1.93-54.1 7.77-80.31 15.04L256 32v128c60.2 0 79.94 15.62 104.73 32 28.57 18.88 69.82 32 104.73 32C555.82 224 640 192 640 128c0-45.22-39.1-97.3-148.58-120.81z\"><\/path><\/svg>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">GESCHLOSSENE SCHUHE TRAGEN<\/h3>            <\/div>\n                    <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b712c71 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"b712c71\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35fb7f3 eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"35fb7f3\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-glasses\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M574.1 280.37L528.75 98.66c-5.91-23.7-21.59-44.05-43-55.81-21.44-11.73-46.97-14.11-70.19-6.33l-15.25 5.08c-8.39 2.79-12.92 11.86-10.12 20.24l5.06 15.18c2.79 8.38 11.85 12.91 20.23 10.12l13.18-4.39c10.87-3.62 23-3.57 33.16 1.73 10.29 5.37 17.57 14.56 20.37 25.82l38.46 153.82c-22.19-6.81-49.79-12.46-81.2-12.46-34.77 0-73.98 7.02-114.85 26.74h-73.18c-40.87-19.74-80.08-26.75-114.86-26.75-31.42 0-59.02 5.65-81.21 12.46l38.46-153.83c2.79-11.25 10.09-20.45 20.38-25.81 10.16-5.3 22.28-5.35 33.15-1.73l13.17 4.39c8.38 2.79 17.44-1.74 20.23-10.12l5.06-15.18c2.8-8.38-1.73-17.45-10.12-20.24l-15.25-5.08c-23.22-7.78-48.75-5.41-70.19 6.33-21.41 11.77-37.09 32.11-43 55.8L1.9 280.37A64.218 64.218 0 0 0 0 295.86v70.25C0 429.01 51.58 480 115.2 480h37.12c60.28 0 110.37-45.94 114.88-105.37l2.93-38.63h35.75l2.93 38.63C313.31 434.06 363.4 480 423.68 480h37.12c63.62 0 115.2-50.99 115.2-113.88v-70.25c0-5.23-.64-10.43-1.9-15.5zm-370.72 89.42c-1.97 25.91-24.4 46.21-51.06 46.21H115.2C86.97 416 64 393.62 64 366.11v-37.54c18.12-6.49 43.42-12.92 72.58-12.92 23.86 0 47.26 4.33 69.93 12.92l-3.13 41.22zM512 366.12c0 27.51-22.97 49.88-51.2 49.88h-37.12c-26.67 0-49.1-20.3-51.06-46.21l-3.13-41.22c22.67-8.59 46.08-12.92 69.95-12.92 29.12 0 54.43 6.44 72.55 12.93v37.54z\"><\/path><\/svg>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">SEINE BRILLE BEFESTIGEN<\/h3>            <\/div>\n                    <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0422aee e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"0422aee\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c305bb0 eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"c305bb0\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-box\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M509.5 184.6L458.9 32.8C452.4 13.2 434.1 0 413.4 0H272v192h238.7c-.4-2.5-.4-5-1.2-7.4zM240 0H98.6c-20.7 0-39 13.2-45.5 32.8L2.5 184.6c-.8 2.4-.8 4.9-1.2 7.4H240V0zM0 224v240c0 26.5 21.5 48 48 48h416c26.5 0 48-21.5 48-48V224H0z\"><\/path><\/svg>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">DIE KANISTER GUT VERSCHLIESSEN<\/h3>            <\/div>\n                    <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a5aad30 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"a5aad30\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb62015 eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"eb62015\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-child\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M120 72c0-39.765 32.235-72 72-72s72 32.235 72 72c0 39.764-32.235 72-72 72s-72-32.236-72-72zm254.627 1.373c-12.496-12.497-32.758-12.497-45.254 0L242.745 160H141.254L54.627 73.373c-12.496-12.497-32.758-12.497-45.254 0-12.497 12.497-12.497 32.758 0 45.255L104 213.254V480c0 17.673 14.327 32 32 32h16c17.673 0 32-14.327 32-32V368h16v112c0 17.673 14.327 32 32 32h16c17.673 0 32-14.327 32-32V213.254l94.627-94.627c12.497-12.497 12.497-32.757 0-45.254z\"><\/path><\/svg>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">VERBOTEN F\u00dcR KINDER UNTER 5 JAHREN<\/h3>            <\/div>\n                    <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>WE ARE YELLOW Entdecken Sie die Preise von Cano\u00ebs Loisirs Sind Sie bereit f\u00fcr ein unvergessliches Abenteuer auf der Dordogne ? Entdecken Sie unsere Streckenoptionen und unsere attraktiven Preise f\u00fcr ein einzigartiges Kanu-Erlebnis. Egal, ob Sie Anf\u00e4nger oder Fortgeschrittener sind, allein, mit der Familie oder mit Freunden, wir haben die passende Strecke f\u00fcr Sie. Parcours Erwachsener im Kanu Kind von 5 bis 12 Jahren im Kanu der Eltern Einsitzer-Kajak \/ Doppelkajak Carsac &gt; Vitrac Der Wittling von Montfort 17\u20ac 10.5\u20ac 20\u20ac Calviac &gt; Vitrac Natur-Parcours 23\u20ac 14\u20ac 26\u20ac Vitrac &gt; Castelnaud Tal der 2 Schl\u00f6sser 20\u20ac 12\u20ac 23\u20ac Vitrac &gt; Beynac Tal der 5 Schl\u00f6sser 22\u20ac 13\u20ac 25\u20ac Carsac &gt; Beynac Tal der 6 Schl\u00f6sser 26\u20ac 15\u20ac 29\u20ac Angepasstes Material Unsere Kanu-Basis ist mit allem ausgestattet, was Sie brauchen, um ein 100%iges Naturabenteuer entlang der Dordogne zu genie\u00dfen. Unsere Kanus und Kajaks mit bequemen R\u00fcckenlehnen sorgen daf\u00fcr, dass Sie ein angenehmes Erlebnis haben werden ! Ein kostenloser Topo-Guide ! Ein Flussf\u00fchrer, der in f\u00fcnf Sprachen verf\u00fcgbar ist, wird Ihnen kostenlos zur Verf\u00fcgung gestellt. Dieser Reisef\u00fchrer hilft Ihnen, den historischen Reichtum des Flusses Esperance zu entdecken, die Qualit\u00e4t dieser gesch\u00fctzten Umgebung zu sch\u00e4tzen und praktische Informationen zu finden. Au\u00dfergew\u00f6hnlicher Kundenservice Unsere Basis liegt im Herzen des majest\u00e4tischen Dordogne-Tals und bietet ab 9 Uhr einen Shuttle-Bus an, der Sie zu den von Ihnen gew\u00e4hlten Startpunkten bringt. Anschlie\u00dfend fahren Sie in Ihrem eigenen Tempo die Dordogne hinunter und kehren zu unserer Basis zur\u00fcck, wo Ihr Auto auf Sie wartet. Auf dem Programm stehen Entspannung, Baden, Picknicks in v\u00f6lliger Freiheit&#8230; Genie\u00dfen Sie es in vollen Z\u00fcgen! Cano\u00ebs Loisirs DIE REGELN ZURESPEKTIEREN ? Damit Ihr Kanuabenteuer sicher und f\u00fcr alle Beteiligten angenehm ist, sollten Sie unbedingt einige einfache Regeln beachten. Diese Anweisungen garantieren nicht nur Ihre Sicherheit, sondern auch die Erhaltung der au\u00dfergew\u00f6hnlichen nat\u00fcrlichen Umgebung der Dordogne. Bitte nehmen Sie sich einen Moment Zeit, um sie sorgf\u00e4ltig zu lesen, bevor Sie mit dem Abstieg beginnen. Lassen Sie uns gemeinsam daf\u00fcr sorgen, dass diese Erfahrung f\u00fcr alle Teilnehmer und f\u00fcr zuk\u00fcnftige Generationen unvergesslich bleibt. SCHWIMMEN K\u00d6NNEN 25 UND UNTERTAUCHEN Tragen einer Schwimmweste In der Mitte des Flusses segeln AN \u00c4STEN UND BAUMST\u00c4MMEN VORBEIFAHREN BADEGEBIETE UMGEHEN DIE NATUR RESPEKTIEREN DIE FISCHER RESPEKTIEREN H\u00d6FLICH ZU ANWOHNERN UND ANDEREN FLUSSBENUTZERN SEIN GESCHLOSSENE SCHUHE TRAGEN SEINE BRILLE BEFESTIGEN DIE KANISTER GUT VERSCHLIESSEN VERBOTEN F\u00dcR KINDER UNTER 5 JAHREN<\/p>\n","protected":false},"author":8105,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-22349","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/canoes-loisirs.com\/de\/wp-json\/wp\/v2\/pages\/22349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canoes-loisirs.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/canoes-loisirs.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/canoes-loisirs.com\/de\/wp-json\/wp\/v2\/users\/8105"}],"replies":[{"embeddable":true,"href":"https:\/\/canoes-loisirs.com\/de\/wp-json\/wp\/v2\/comments?post=22349"}],"version-history":[{"count":7,"href":"https:\/\/canoes-loisirs.com\/de\/wp-json\/wp\/v2\/pages\/22349\/revisions"}],"predecessor-version":[{"id":22838,"href":"https:\/\/canoes-loisirs.com\/de\/wp-json\/wp\/v2\/pages\/22349\/revisions\/22838"}],"wp:attachment":[{"href":"https:\/\/canoes-loisirs.com\/de\/wp-json\/wp\/v2\/media?parent=22349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}